{"id":41902,"date":"2026-02-03T09:11:48","date_gmt":"2026-02-03T08:11:48","guid":{"rendered":"https:\/\/altoo.io\/?p=41902"},"modified":"2026-02-09T18:36:47","modified_gmt":"2026-02-09T17:36:47","slug":"pourquoi-les-family-offices-ne-peuvent-pas-se-permettre-dignorer-le-portefeuille","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/why-family-offices-cant-afford-portfolio-blindness\/","title":{"rendered":"Pourquoi les Family Offices ne Peuvent Pas se Permettre d'\u00eatre Aveugles en Mati\u00e8re de Gestion de Portefeuille"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"41902\" class=\"elementor elementor-41902\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4d1ba0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4d1ba0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2026d38\" data-id=\"2026d38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efaa903 elementor-widget elementor-widget-text-editor\" data-id=\"efaa903\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Quand<\/span><a href=\"https:\/\/www.rbcwealthmanagement.com\/en-us\/newsroom\/2025-10-16\/2025-rbc-and-campden-wealth-report-north-american-family-offices-adapt-to-uncertainty-and-embrace-ai-innovation\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">RBC et Campden Wealth ont interrog\u00e9 317 family offices en 2025.<\/span><\/a><span style=\"font-weight: 400;\">, ils ont constat\u00e9 que les processus manuels et la d\u00e9pendance excessive \u00e0 l'\u00e9gard des feuilles de calcul \u00e9taient les risques op\u00e9rationnels les plus fr\u00e9quemment cit\u00e9s. Les processus manuels de traitement des donn\u00e9es doivent \u00eatre ex\u00e9cut\u00e9s par des personnes, qui sont relativement peu nombreuses dans les family offices. <\/span><a href=\"https:\/\/www.goldmansachs.com\/pressroom\/press-releases\/2025\/2025-family-office-investment-insights-report-press-release\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">l''enqu\u00eate 2025 de Goldman Sachs aupr\u00e8s de 245 family offices<\/span><\/a><span style=\"font-weight: 400;\"> a r\u00e9v\u00e9l\u00e9 que 62% disposent d'\u00e9quipes d'investissement compos\u00e9es de moins de cinq membres. Ces \u00e9quipes restreintes g\u00e8rent des portefeuilles d'une valeur moyenne de 1,1 milliard d'USD r\u00e9partis entre les actions publiques (31%), le capital-investissement (21%), l'immobilier, les titres \u00e0 revenu fixe et les actifs alternatifs. Les family offices g\u00e9rant des portefeuilles de plus en plus diversifi\u00e9s, le manque de donn\u00e9es se creuse pr\u00e9cis\u00e9ment l\u00e0 o\u00f9 la visibilit\u00e9 est la plus importante.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3216e5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3216e5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d6edc9\" data-id=\"1d6edc9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b0022b elementor-widget elementor-widget-heading\" data-id=\"6b0022b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">La norme institutionnelle<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8c15f8 elementor-widget elementor-widget-text-editor\" data-id=\"e8c15f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les gestionnaires d'actifs institutionnels ont cherch\u00e9 \u00e0 r\u00e9soudre le probl\u00e8me de la multi-d\u00e9positaire en investissant massivement dans la technologie et en mettant en place une infrastructure sp\u00e9cialis\u00e9e. A titre d'exemple,<\/span><a href=\"https:\/\/www.ainvest.com\/news\/state-street-strategic-deepening-asset-servicing-capabilities-implications-institutional-investors-2508\/\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">State Street investit 2 milliards de dollars par an<\/span><\/a><span style=\"font-weight: 400;\"> dans le d\u00e9veloppement technologique ax\u00e9 sur l'harmonisation des donn\u00e9es tout au long du cycle de vie de l'\u00e9valuation des portefeuilles (num\u00e9risation des flux de travail administratifs et automatisation des processus de r\u00e9conciliation).\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Les normes industrielles renforcent cette approche. Les normes de l'industrie renforcent cette approche.<\/span><a href=\"https:\/\/rpc.cfainstitute.org\/gips-standards\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">Les normes mondiales de performance des investissements (GIPS) du CFA Institute<\/span><\/a><span style=\"font-weight: 400;\"> exigent une construction composite et un calcul de performance standardis\u00e9 pour tous les portefeuilles r\u00e9els, discr\u00e9tionnaires et payants. En d\u00e9cembre 2023, 1 778 organisations revendiqueront la conformit\u00e9 aux GIPS, une norme impossible \u00e0 respecter sans une vision consolid\u00e9e des portefeuilles. Pour les investisseurs institutionnels, la consolidation en temps r\u00e9el n'est pas un avantage concurrentiel ; c'est une exigence de conformit\u00e9 et une n\u00e9cessit\u00e9 op\u00e9rationnelle.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-accc860 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"accc860\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bdc49b1\" data-id=\"bdc49b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aeb5d37 elementor-widget elementor-widget-heading\" data-id=\"aeb5d37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">La r\u00e9alit\u00e9 du Family Office\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f1ed09 elementor-widget elementor-widget-text-editor\" data-id=\"5f1ed09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les family offices sont confront\u00e9s \u00e0 la m\u00eame complexit\u00e9 multi-d\u00e9positaire que les institutions, mais ils op\u00e8rent \u00e0 des \u00e9chelles radicalement diff\u00e9rentes. Le family office type ne dispose pas des ressources n\u00e9cessaires pour reproduire l'infrastructure institutionnelle. Avec des \u00e9quipes d'investissement de moins de cinq personnes g\u00e9rant des portefeuilles d'un milliard de dollars, la consolidation manuelle consomme des ressources qui devraient \u00eatre consacr\u00e9es \u00e0 la strat\u00e9gie et \u00e0 la prise de d\u00e9cision.<\/span><\/p><p><span style=\"font-weight: 400;\">L'infrastructure des d\u00e9positaires ne fait qu'aggraver ce probl\u00e8me. De nombreux d\u00e9positaires utilisent des plateformes propri\u00e9taires qui peuvent dater de plusieurs dizaines d'ann\u00e9es. Ce manque de compatibilit\u00e9 oblige souvent les family offices \u00e0 mettre en \u0153uvre des solutions de conservation en tant que syst\u00e8mes autonomes, ce qui n\u00e9cessite une r\u00e9conciliation manuelle qui introduit des erreurs et des retards. Alors que les investisseurs institutionnels n\u00e9gocient des int\u00e9grations d'entreprise et des flux de donn\u00e9es directs, les family offices n'ont g\u00e9n\u00e9ralement pas l'envergure n\u00e9cessaire pour exiger des am\u00e9nagements similaires.<\/span><\/p><p><span style=\"font-weight: 400;\">L'allocation aux march\u00e9s priv\u00e9s intensifie le d\u00e9fi des donn\u00e9es. \u00c0 mesure que les family offices augmentent leur exposition au capital-investissement, au capital-risque et aux actifs r\u00e9els, ils sont confront\u00e9s \u00e0 des classes d'actifs qui r\u00e9sistent \u00e0 la normalisation. Les appels de fonds arrivent sous forme d'avis PDF plut\u00f4t que de donn\u00e9es structur\u00e9es. Les valorisations sont mises \u00e0 jour trimestriellement plut\u00f4t que quotidiennement. Les mesures de performance (IRR, TVPI, DPI) diff\u00e8rent fondamentalement des rendements des march\u00e9s publics.\u00a0<\/span><\/p><p><a href=\"https:\/\/www.pwmnet.com\/content\/d8b1d55f-0697-524f-8445-26f3950ea94c\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">L'\u00e9tude 2025 de Professional Wealth Management<\/span><\/a><span style=\"font-weight: 400;\"> identifie le co\u00fbt et la complexit\u00e9 de la mise en \u0153uvre comme les principaux obstacles \u00e0 l'adoption de la technologie. La plupart des plateformes ont \u00e9t\u00e9 con\u00e7ues pour les fonds sp\u00e9culatifs et les investisseurs institutionnels, laissant les family offices aux prises avec une lenteur d'int\u00e9gration, des rapports fragment\u00e9s et un manque d'informations en temps r\u00e9el. Les solutions institutionnelles existent, mais elles n'ont pas \u00e9t\u00e9 con\u00e7ues pour l'\u00e9chelle et la complexit\u00e9 des family offices.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fa7b4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fa7b4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad76e70\" data-id=\"ad76e70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d301a52 elementor-widget elementor-widget-heading\" data-id=\"d301a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">L'imp\u00e9ratif de r\u00e9conciliation<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b0a0f8 elementor-widget elementor-widget-text-editor\" data-id=\"5b0a0f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La consolidation des portefeuilles n'apporte de la valeur que si les donn\u00e9es sous-jacentes s'av\u00e8rent fiables. La r\u00e9conciliation manuelle consomme traditionnellement des ressources importantes, tant pour les institutions que pour les family offices.<\/span><\/p><p><span style=\"font-weight: 400;\">Les am\u00e9liorations op\u00e9rationnelles apport\u00e9es par State Street en 2025 mettent l'accent sur le rapprochement automatis\u00e9, qui est au c\u0153ur de leur proposition de valeur. En consolidant les fournisseurs et en automatisant les processus, l'entreprise a r\u00e9duit ses co\u00fbts op\u00e9rationnels et am\u00e9lior\u00e9 sa r\u00e9activit\u00e9 face aux besoins des clients. L'automatisation acc\u00e9l\u00e8re les flux de travail existants et modifie fondamentalement les sch\u00e9mas d'erreur en \u00e9liminant la transcription manuelle, les erreurs de formule et les probl\u00e8mes de contr\u00f4le de version qui accompagnent presque toujours les approches bas\u00e9es sur des feuilles de calcul.<\/span><\/p><p><span style=\"font-weight: 400;\">Pour les family offices, la complexit\u00e9 de la r\u00e9conciliation se multiplie avec chaque relation suppl\u00e9mentaire avec le d\u00e9positaire. Lorsque les relev\u00e9s arrivent dans des formats, des devises et des sch\u00e9mas de classification des actifs diff\u00e9rents, le rapprochement des positions n\u00e9cessite non seulement la saisie des donn\u00e9es, mais aussi leur traduction et leur normalisation. Une position en actions libell\u00e9e en USD d\u00e9tenue par un courtier am\u00e9ricain, une obligation libell\u00e9e en CHF d\u00e9tenue par une banque suisse et un engagement en private equity libell\u00e9 en EUR d\u00e9tenu par un administrateur de fonds luxembourgeois font chacun l'objet d'un rapport diff\u00e9rent. Sans rapprochement automatis\u00e9, le personnel du family office v\u00e9rifie manuellement que le m\u00eame titre n'est pas comptabilis\u00e9 deux fois, que les mouvements de tr\u00e9sorerie s'\u00e9quilibrent entre les comptes et que les calculs de performance utilisent des sources de prix coh\u00e9rentes.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c6a53d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c6a53d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d96a9ed\" data-id=\"d96a9ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b88be21 elementor-widget elementor-widget-heading\" data-id=\"b88be21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">La technologie en tant qu'infrastructure<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac78ff9 elementor-widget elementor-widget-text-editor\" data-id=\"ac78ff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L'\u00e9cart entre les capacit\u00e9s institutionnelles et les op\u00e9rations des family offices ne refl\u00e8te pas un d\u00e9ficit de connaissances mais une contrainte d'infrastructure. Les investisseurs institutionnels ont construit ou achet\u00e9 la technologie qui permet une consolidation en temps quasi r\u00e9el. Les family offices ont besoin de capacit\u00e9s similaires mais n'ont pas la m\u00eame \u00e9chelle organisationnelle.<\/span><\/p><p><span style=\"font-weight: 400;\">Les plates-formes technologiques sp\u00e9cialis\u00e9es comblent cette lacune en offrant une consolidation de niveau institutionnel sans investissement \u00e0 l'\u00e9chelle de l'institution. La solution optimale offre une connectivit\u00e9 automatis\u00e9e avec des milliers de d\u00e9positaires, normalise les donn\u00e9es en fonction des formats et des devises, prend en charge les actifs traditionnels et alternatifs, et assure une r\u00e9conciliation de qualit\u00e9, le tout par le biais d'interfaces con\u00e7ues pour des utilisateurs non techniques. Plut\u00f4t que de n\u00e9gocier l'int\u00e9gration de chaque d\u00e9positaire, les family offices b\u00e9n\u00e9ficient d'un acc\u00e8s imm\u00e9diat \u00e0 des connexions pr\u00e9d\u00e9finies. Plut\u00f4t que de maintenir des \u00e9quipes internes de normalisation des donn\u00e9es, ils s'appuient sur des plateformes qui g\u00e8rent automatiquement la traduction des formats.<\/span><\/p><p><span style=\"font-weight: 400;\">Le passage d'une visibilit\u00e9 fragment\u00e9e \u00e0 une intelligence consolid\u00e9e permet une approche fondamentalement diff\u00e9rente de la gestion de portefeuille. Lorsque toutes les positions sont mises \u00e0 jour rapidement et automatiquement, les \u00e9carts par rapport aux objectifs d'allocation strat\u00e9gique deviennent imm\u00e9diatement visibles. Lorsque les donn\u00e9es de performance sont agr\u00e9g\u00e9es entre les diff\u00e9rents d\u00e9positaires, la comparaison des gestionnaires et le contr\u00f4le pr\u00e9alable s'en trouvent am\u00e9lior\u00e9s. Lorsque la r\u00e9conciliation se fait automatiquement, les \u00e9quipes des family offices r\u00e9orientent leur attention de l'administration des donn\u00e9es vers la prise de d\u00e9cision strat\u00e9gique.<\/span><\/p><p><span style=\"font-weight: 400;\">L'imp\u00e9ratif de consolidation d\u00e9coule d'une r\u00e9alit\u00e9 simple : on ne peut pas g\u00e9rer ce que l'on ne voit pas. La c\u00e9cit\u00e9 du portefeuille - l'incapacit\u00e9 de visualiser l'ensemble des avoirs avec pr\u00e9cision - cr\u00e9e un risque qui se r\u00e9percute sur toutes les d\u00e9cisions d'investissement. Les objectifs d'allocation strat\u00e9gique, les opportunit\u00e9s de r\u00e9\u00e9quilibrage et le potentiel de r\u00e9cup\u00e9ration des pertes fiscales sont manqu\u00e9s. Les concentrations de risques s'accumulent de mani\u00e8re invisible. Chaque lacune repr\u00e9sente un \u00e9chec de la pr\u00e9servation du patrimoine ou un co\u00fbt d'opportunit\u00e9 qui s'accumule au fil du temps.<\/span><\/p><p><span style=\"font-weight: 400;\">La plateforme Altoo Wealth Platform r\u00e9pond \u00e0 ce d\u00e9fi de consolidation en se connectant \u00e0 plus de 3 500 institutions d\u00e9positaires et non d\u00e9positaires, et en prenant en charge plus de 40 types d'actifs, des actions et obligations traditionnelles au private equity, en passant par l'immobilier et les objets de collection. L'importation et le rapprochement automatis\u00e9s des donn\u00e9es \u00e9liminent les erreurs de saisie manuelle tout en respectant les normes de s\u00e9curit\u00e9 et de cryptage h\u00e9berg\u00e9es en Suisse. Les tableaux de bord visuels de la plateforme offrent une visibilit\u00e9 en temps r\u00e9el du portefeuille qui est mis \u00e0 jour en continu plut\u00f4t que par le biais d'une r\u00e9conciliation en fin de mois, ce qui permet aux family offices de g\u00e9rer leur patrimoine avec une intelligence de niveau institutionnel \u00e0 l'\u00e9chelle appropri\u00e9e.<\/span><\/p><p><span style=\"font-weight: 400;\"><a href=\"https:\/\/altoo.io\/fr\/nous-contacter\/\" target=\"_blank\" rel=\"noopener\">Contactez-Nous<\/a> pour une d\u00e9monstration afin de voir comment la Plateforme Altoo Wealth transforme les donn\u00e9es fragment\u00e9es des portefeuilles en intelligence consolid\u00e9e - avec la m\u00eame rigueur que vous appliquez \u00e0 tous les autres aspects de la gestion de patrimoine.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pour les family offices, il n'est que trop facile de transformer les strat\u00e9gies de diversification en passif op\u00e9rationnel.  Lorsque les d\u00e9positaires, les classes d'actifs et les juridictions sont multiples, les structures destin\u00e9es \u00e0 prot\u00e9ger la richesse peuvent l'obscurcir. Malheureusement, la persistance d'une consolidation bas\u00e9e sur des feuilles de calcul est le sympt\u00f4me d'un manque d'infrastructure. Heureusement, les family offices peuvent s'inspirer de la mani\u00e8re dont les investisseurs institutionnels comblent cette lacune.<\/p>","protected":false},"author":12,"featured_media":41903,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,86,233,89,88,87],"tags":[817,1032],"class_list":["post-41902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-explore-by-entity","category-family-office","category-multi-family-office","category-private-wealth-owners","category-single-family-office","tag-risk-management","tag-template-3"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/41902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=41902"}],"version-history":[{"count":9,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/41902\/revisions"}],"predecessor-version":[{"id":42166,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/41902\/revisions\/42166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/41903"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=41902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=41902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=41902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}