{"id":27305,"date":"2023-11-17T10:00:36","date_gmt":"2023-11-17T09:00:36","guid":{"rendered":"https:\/\/altoo.io\/?p=27305"},"modified":"2023-11-17T09:29:10","modified_gmt":"2023-11-17T08:29:10","slug":"la-fondation-lauder-une-puissance-philanthropique","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/the-lauder-foundation-a-philanthropic-powerhouse\/","title":{"rendered":"La Fondation Lauder : Une Puissance Philanthropique"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"27305\" class=\"elementor elementor-27305\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bba4391 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bba4391\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da9945f\" data-id=\"da9945f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cde3d07 elementor-widget elementor-widget-text-editor\" data-id=\"cde3d07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Contexte et mission<\/b><\/h4><p><span style=\"font-weight: 400;\">Leonard et Evelyn Lauder, h\u00e9ritiers de la fortune des cosm\u00e9tiques Est\u00e9e Lauder, ont consacr\u00e9 leur vie \u00e0 la philanthropie et \u00e0 faire la diff\u00e9rence dans le monde. La Fondation a \u00e9t\u00e9 cr\u00e9\u00e9e pour canaliser leurs ressources et leur influence vers des causes qui leur tiennent \u00e0 c\u0153ur. Bien que la Fondation reste discr\u00e8te, son impact est consid\u00e9rable. Elle soutient en particulier des organisations qui promeuvent la d\u00e9mocratie, le d\u00e9veloppement mondial, l'\u00e9ducation, les arts et la culture, les causes juives et la recherche sur les maladies.<\/span><\/p><p>\u00a0<\/p><h4><b>Octroi de subventions et domaines d'intervention<\/b><\/h4><p><span style=\"font-weight: 400;\">L'un des principaux b\u00e9n\u00e9ficiaires de la Fondation Lauder est l'Institut Aspen, une organisation qui se consacre \u00e0 la promotion du leadership et \u00e0 la r\u00e9solution des probl\u00e8mes mondiaux. En tant qu'administrateur et pr\u00e9sident du comit\u00e9 international de l'Institut, Leonard Lauder a jou\u00e9 un r\u00f4le essentiel dans l'\u00e9laboration des programmes et des initiatives de l'Institut. La Fondation a apport\u00e9 un soutien financier important \u00e0 l'Aspen Institute, totalisant environ 780 000 dollars au cours des derni\u00e8res ann\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">La Fondation Lauder donne la priorit\u00e9 \u00e0 une \u00e9ducation de qualit\u00e9 et soutient les \u00e9coles primaires et secondaires, en particulier les \u00e9tablissements priv\u00e9s de pr\u00e9paration \u00e0 l'universit\u00e9 tels que la Pilgrim School \u00e0 Los Angeles, la Lake Highland Preparatory School et la First Academy \u00e0 Orlando, en Floride. Elle soutient \u00e9galement des programmes \u00e9ducatifs dans des biblioth\u00e8ques publiques, telles que la Greenwich Library dans le Connecticut et la Winter Park Public Library en Floride. Dans le domaine de l'enseignement sup\u00e9rieur, la fondation a soutenu le Hunter College et le Army War College. Ses d\u00e9clarations fiscales t\u00e9moignent d'un engagement fort en faveur d'une \u00e9ducation compl\u00e8te, de la maternelle \u00e0 la terminale.<\/span><\/p><p><span style=\"font-weight: 400;\">Bien que la Fondation Lauder n'indique pas explicitement ses priorit\u00e9s en mati\u00e8re de subventionnement des arts et de la culture, ses d\u00e9clarations fiscales r\u00e9v\u00e8lent un int\u00e9r\u00eat marqu\u00e9 pour le soutien d'une vari\u00e9t\u00e9 d'organisations culturelles. Parmi les b\u00e9n\u00e9ficiaires r\u00e9cents figurent des institutions prestigieuses telles que la Frick Collection, le Metropolitan Opera, les jardins botaniques de New York et la Statue of Liberty\/Ellis Island Foundation. L'engagement de la Fondation en faveur des arts et de la culture s'\u00e9tend au-del\u00e0 de la ville de New York, avec le soutien apport\u00e9 au Glimmerglass Opera Theatre \u00e0 Cooperstown, dans l'\u00c9tat de New York.<\/span><\/p><p><span style=\"font-weight: 400;\">La Fondation Lauder s'est engag\u00e9e depuis longtemps \u00e0 soutenir des causes juives. Bien que ce domaine ne repr\u00e9sente qu'une petite partie de l'ensemble de ses subventions, la fondation a accord\u00e9 des subventions \u00e0 un large \u00e9ventail d'organisations juives \u00e0 travers les \u00c9tats-Unis. Parmi les b\u00e9n\u00e9ficiaires figurent le National Museum of American Jewish History, le Jewish Communal Fund, la Gideon Hausner Jewish Day School en Californie, l'American Jewish Committee et le National Jewish Health, un h\u00f4pital de recherche situ\u00e9 \u00e0 Denver, dans le Colorado.<\/span><\/p><p><span style=\"font-weight: 400;\">Bien que la Fondation Lauder ne se consacre pas principalement \u00e0 la recherche sur les maladies, elle a apport\u00e9 des contributions notables dans ce domaine. La fondation a accord\u00e9 des subventions \u00e0 des organisations d\u00e9di\u00e9es \u00e0 la recherche, \u00e0 la pr\u00e9vention et au traitement des maladies. Elle a notamment soutenu l'Elton John AIDS Foundation et l'Alzheimer's Drug Discovery Foundation, dont Leonard Lauder est le copr\u00e9sident. La famille Lauder s'est engag\u00e9e \u00e0 verser 200 millions de dollars jusqu'en 2033 pour acc\u00e9l\u00e9rer la recherche sur le traitement et la pr\u00e9vention de la maladie d'Alzheimer.<\/span><\/p><p>\u00a0<\/p><h4><b>Impact et d\u00e9tails de la subvention<\/b><\/h4><p><span style=\"font-weight: 400;\">Ces derni\u00e8res ann\u00e9es, la Fondation Lauder a toujours accord\u00e9 entre 3 et 4 millions de dollars de subventions par an. Les subventions de la Fondation vont de 2 000 \u00e0 1 million de dollars, les montants les plus \u00e9lev\u00e9s \u00e9tant g\u00e9n\u00e9ralement attribu\u00e9s \u00e0 des organisations dans lesquelles Leonard Lauder est personnellement impliqu\u00e9. L'impact de la Fondation est \u00e9vident dans les nombreux organismes et projets qu'elle a soutenus, \u00e0 la fois dans la ville de New York et en dehors. L'engagement de la Fondation en faveur d'un soutien continu et l'implication personnelle de son fondateur lui ont permis de faire une diff\u00e9rence significative dans la vie des individus et des communaut\u00e9s.<\/span><\/p><p><span style=\"font-weight: 400;\">La Fondation Lauder, dirig\u00e9e par Leonard et Evelyn Lauder, est devenue une puissance philanthropique \u00e0 New York. S'attachant \u00e0 soutenir des causes qui correspondent aux int\u00e9r\u00eats personnels des fondateurs, la fondation a apport\u00e9 des contributions significatives dans les domaines de l'\u00e9ducation, des arts et de la culture, des causes juives et de la recherche sur les maladies. M\u00eame si la fondation n'est pas facilement accessible aux nouvelles organisations, son impact est ind\u00e9niable. Le soutien continu de la Fondation Lauder et son engagement en faveur d'un changement positif ont laiss\u00e9 un h\u00e9ritage durable dans la communaut\u00e9, faisant d'elle un phare d'espoir et de progr\u00e8s pour les personnes dans le besoin.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La Fondation Lauder est une importante organisation philanthropique bas\u00e9e \u00e0 New York. Cr\u00e9\u00e9e en 1987 par Leonard A. Lauder, fils de l'entrepreneur en cosm\u00e9tiques Est\u00e9e Lauder, et son \u00e9pouse Evelyn, la fondation a apport\u00e9 des contributions significatives dans divers domaines, notamment l'\u00e9ducation, les arts et la culture, les causes juives et la recherche sur les maladies. En s'attachant \u00e0 soutenir des organisations qui correspondent aux int\u00e9r\u00eats personnels de ses fondateurs, la Fondation Lauder a jou\u00e9 un r\u00f4le essentiel dans la promotion d'un changement positif au sein de la communaut\u00e9.<\/p>","protected":false},"author":12,"featured_media":27387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,73,57,545,82,67],"tags":[834],"class_list":["post-27305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-explore-by-topic","category-lifestyle","category-people","category-philantrophy","category-philantropy","tag-lauder-foundation"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/27305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=27305"}],"version-history":[{"count":8,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/27305\/revisions"}],"predecessor-version":[{"id":27384,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/27305\/revisions\/27384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/27387"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=27305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=27305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=27305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}