{"id":24479,"date":"2023-12-26T10:00:04","date_gmt":"2023-12-26T09:00:04","guid":{"rendered":"https:\/\/altoo.io\/?p=24479"},"modified":"2023-12-26T09:23:29","modified_gmt":"2023-12-26T08:23:29","slug":"lere-numerique-et-les-gestionnaires-de-patrimoine-ce-qui-change","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/digital-age-and-wealth-managers-what-is-changing\/","title":{"rendered":"L'\u00e8re Num\u00e9rique et les Gestionnaires de Patrimoine : Ce qui Change"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"24479\" class=\"elementor elementor-24479\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df0b522 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df0b522\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af4074f\" data-id=\"af4074f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e58f1b2 elementor-widget elementor-widget-text-editor\" data-id=\"e58f1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pour les gestionnaires de patrimoine qui naviguent dans ce paysage au nom des UHNWI et des HNWI, l'adaptation est devenue n\u00e9cessaire. Cet article examine comment les professionnels de la finance, les gestionnaires de patrimoine et les conseillers en investissement r\u00e9inventent leur r\u00f4le. Ils doivent veiller \u00e0 ce que l'essence m\u00eame de la confiance et de l'intuition humaine ne soit pas perdue au milieu des codes binaires et des canaux crypt\u00e9s.<\/span><\/p><p><span style=\"font-weight: 400;\">La voie \u00e0 suivre consiste \u00e0 combiner les principes s\u00e9culaires de la gestion de patrimoine avec les solutions innovantes d'aujourd'hui.\u00a0<\/span><\/p><p>\u00a0<\/p><h3><b>La transition num\u00e9rique dans la gestion de patrimoine\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">Les racines de la gestion de patrimoine remontent \u00e0 loin, avec des si\u00e8cles de confiance, de conseils personnalis\u00e9s et de strat\u00e9gies complexes con\u00e7ues pour les personnes fortun\u00e9es. Ce parcours historique, qui va des intendants de l'Antiquit\u00e9 aux conseillers financiers sophistiqu\u00e9s d'aujourd'hui, t\u00e9moigne de l'\u00e9volution constante d'une profession. La qu\u00eate incessante n'\u00e9tait pas seulement de sauvegarder et d'accro\u00eetre la richesse, mais aussi de suivre l'\u00e9volution du paysage socio-\u00e9conomique et technologique.<\/span><\/p><p><span style=\"font-weight: 400;\">Toutefois, les derni\u00e8res d\u00e9cennies ont vu s'acc\u00e9l\u00e9rer le rythme des changements, remettant en cause le tissu m\u00eame de ce secteur. Il ne s'agit plus de tenir des registres et des coffres-forts physiques. La r\u00e9volution num\u00e9rique, souvent qualifi\u00e9e de quatri\u00e8me r\u00e9volution industrielle, a marqu\u00e9 la gestion de patrimoine de son empreinte, comme elle l'a fait pour d'autres secteurs. Des algorithmes sophistiqu\u00e9s pr\u00e9disant les mouvements du march\u00e9 aux tableaux de bord des clients fournissant des \u00e9valuations d'actifs en temps r\u00e9el, les outils num\u00e9riques deviennent rapidement essentiels.<\/span><\/p><p><span style=\"font-weight: 400;\">Pour les clients UHNWI et HNWI, la technologie pr\u00e9sente \u00e0 la fois des promesses et des risques potentiels. D'une part, ils b\u00e9n\u00e9ficient d'un acc\u00e8s in\u00e9gal\u00e9 aux march\u00e9s mondiaux et de la possibilit\u00e9 de diversifier leurs actifs et leurs connaissances, autrefois r\u00e9serv\u00e9s \u00e0 quelques privil\u00e9gi\u00e9s. D'autre part, ils sont confront\u00e9s \u00e0 la menace des cyberattaques, de la d\u00e9sinformation et d'une \u00e9norme quantit\u00e9 de donn\u00e9es financi\u00e8res.<\/span><\/p><p><span style=\"font-weight: 400;\">Les gestionnaires de patrimoine se trouvent \u00e0 l'\u00e9picentre de ces changements. Leur r\u00f4le ne consiste plus seulement \u00e0 comprendre les march\u00e9s. Il s'agit de comprendre les outils qui d\u00e9cryptent ces march\u00e9s. <\/span><a href=\"https:\/\/www.simon-kucher.com\/en\/insights\/wealth-management-younger-generation-hybrid-advice-unlocks-value\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Une majorit\u00e9 d'UHNWIs attendent d\u00e9sormais de leurs conseillers financiers qu'ils soient capables d'int\u00e9grer les outils num\u00e9riques<\/span><\/a><span style=\"font-weight: 400;\"> dans leurs strat\u00e9gies. Et avec l'innovation constante dans le domaine des FinTech, cette attente pourrait encore s'accro\u00eetre.<\/span><\/p><p><span style=\"font-weight: 400;\">Pourtant, cette temp\u00eate num\u00e9rique est accompagn\u00e9e d'une lueur d'espoir. La technologie, tout en remodelant les op\u00e9rations quotidiennes de la gestion de patrimoine, ne diminue pas l'aspect humain du r\u00f4le. Les clients recherchent toujours la confiance qui d\u00e9coule de l'intuition humaine, la confiance forg\u00e9e dans les relations personnelles et l'assurance que derri\u00e8re chaque algorithme, il y a un professionnel d\u00e9vou\u00e9 qui prot\u00e8ge leurs int\u00e9r\u00eats.<\/span><\/p><p><span style=\"font-weight: 400;\">Les gestionnaires de patrimoine peuvent utiliser la technologie de nombreuses fa\u00e7ons pour mieux servir leurs clients UHNWI et HNWI tout en restant fid\u00e8les aux principes qui d\u00e9finissent leur profession depuis des si\u00e8cles.<\/span><\/p><p>\u00a0<\/p><h3><b>R\u00f4le traditionnel ou moderne du gestionnaire de patrimoine<\/b><\/h3><p><span style=\"font-weight: 400;\">La vague num\u00e9rique est le moteur de l'\u00e9volution du paysage financier. Comme tout changement de paradigme, elle pr\u00e9sente \u00e0 la fois des d\u00e9fis et des opportunit\u00e9s. Le r\u00f4le du gestionnaire de patrimoine est au c\u0153ur de cette transformation. Si l'objectif principal - cultiver, prot\u00e9ger et faire fructifier le patrimoine - reste inchang\u00e9, les m\u00e9thodes pour y parvenir \u00e9voluent rapidement. Examinons le contraste entre le r\u00f4le traditionnel et le r\u00f4le moderne des gestionnaires de patrimoine, pour comprendre comment l'essence reste la m\u00eame alors que les outils et les techniques \u00e9voluent.<\/span><\/p><h4><b>Relations personnelles et renforcement de la confiance<\/b><\/h4><p><span style=\"font-weight: 400;\">Historiquement, la gestion de patrimoine \u00e9tait synonyme de relations personnelles. Le gestionnaire de patrimoine traditionnel n'\u00e9tait pas seulement un conseiller, mais un confident, qui comprenait les subtilit\u00e9s du portefeuille financier d'un client et ses aspirations plus g\u00e9n\u00e9rales. Les r\u00e9unions en face \u00e0 face, les notes manuscrites et les longues discussions \u00e9taient la norme.<\/span><\/p><p><span style=\"font-weight: 400;\">Si la technologie a introduit des canaux de communication plus efficaces, l'essence des relations personnelles reste cruciale. Les gestionnaires de patrimoine modernes, au service des UHNWI et des HNWI, comprennent que la confiance ne se construit pas simplement \u00e0 l'aide d'algorithmes ou de points de donn\u00e9es, mais gr\u00e2ce \u00e0 un v\u00e9ritable engagement personnel. Les m\u00e9thodes ont peut-\u00eatre \u00e9volu\u00e9 - avec des r\u00e9unions virtuelles, des chatbots en temps r\u00e9el et des tableaux de bord num\u00e9riques - mais l'objectif reste inchang\u00e9 : forger une confiance profond\u00e9ment enracin\u00e9e.<\/span><\/p><h4><b>Robo-conseillers et d\u00e9cisions algorithmiques<\/b><\/h4><p><span style=\"font-weight: 400;\">Entrez dans le monde des robo-advisors, qui t\u00e9moignent de la fa\u00e7on dont la technologie remod\u00e8le le domaine de la gestion de patrimoine. Ces plateformes num\u00e9riques utilisent des algorithmes math\u00e9matiques pour offrir des conseils d'investissement avec une intervention humaine minimale. <\/span><a href=\"https:\/\/www.pwc.com\/gx\/en\/industries\/financial-services\/asset-management\/publications\/asset-and-wealth-management-revolution-2023.html\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Enqu\u00eate mondiale sur la gestion d'actifs et de patrimoine 2023 de PwC<\/span><\/a><span style=\"font-weight: 400;\"> r\u00e9v\u00e8le que les actifs g\u00e9r\u00e9s par les robo-advisors dans le monde d\u00e9passeront $2,5 trillions en 2022.<\/span><\/p><p><span style=\"font-weight: 400;\">La r\u00e9volution num\u00e9rique oblige les gestionnaires de patrimoine \u00e0 se perfectionner et \u00e0 int\u00e9grer ces technologies dans leur gamme de services. Il est important de comprendre que les robots-conseillers, bien que sophistiqu\u00e9s, peuvent ne pas avoir l'intuition humaine et l'adaptation sur mesure requises pour les portefeuilles financiers complexes, en particulier dans les cat\u00e9gories UHNWI et HNWI.<\/span><\/p><p><span style=\"font-weight: 400;\">Pour le gestionnaire de patrimoine moderne, l'approche consiste \u00e0 combiner l'efficacit\u00e9 et la pr\u00e9cision des d\u00e9cisions algorithmiques avec la profondeur de la compr\u00e9hension et de la perspicacit\u00e9 personnelles. L'utilisation de robots-conseillers pour les d\u00e9cisions de routine pourrait lib\u00e9rer du temps, permettant aux gestionnaires de patrimoine de se concentrer sur la planification strat\u00e9gique, la diversification d'actifs complexes et l'\u00e9laboration de strat\u00e9gies financi\u00e8res sur mesure.<\/span><\/p><p><span style=\"font-weight: 400;\">Le r\u00f4le du gestionnaire de patrimoine moderne ne s'\u00e9loigne pas du traditionnel, il \u00e9volue plut\u00f4t. Il s'agit d'harmoniser le meilleur des deux mondes - les valeurs intemporelles de la confiance et des relations personnelles avec la pr\u00e9cision et l'efficacit\u00e9 des outils num\u00e9riques.\u00a0<\/span><\/p><p>\u00a0<\/p><h3><b>Comp\u00e9tences n\u00e9cessaires dans le monde num\u00e9rique<\/b><\/h3><p><span style=\"font-weight: 400;\">Le r\u00f4le des gestionnaires de patrimoine va bien au-del\u00e0 de la gestion d'actifs traditionnelle \u00e0 une \u00e9poque de progr\u00e8s num\u00e9riques sans pr\u00e9c\u00e9dent. La gestion de patrimoine moderne n\u00e9cessite un m\u00e9lange de sens financier et d'intelligence num\u00e9rique, garantissant que les actifs des UHNWI et HNWI non seulement se d\u00e9veloppent, mais sont \u00e9galement prot\u00e9g\u00e9s des d\u00e9fis contemporains. Examinons deux comp\u00e9tences essentielles que tout gestionnaire de patrimoine devrait envisager de ma\u00eetriser \u00e0 l'\u00e8re du num\u00e9rique.<\/span><\/p><h4><b>Adopter les plateformes Fintech<\/b><\/h4><p><span style=\"font-weight: 400;\">L'\u00e9volution des plateformes fintech a r\u00e9volutionn\u00e9 la fa\u00e7on dont le patrimoine est g\u00e9r\u00e9. Ces plateformes offrent de multiples outils, allant de l'analyse des investissements au suivi des actifs bas\u00e9 sur la blockchain. Pour les gestionnaires de patrimoine qui s'adressent aux UHNWI et aux HNWI, se tenir au courant des derniers d\u00e9veloppements fintech n'est pas seulement une recommandation - c'est une n\u00e9cessit\u00e9.<\/span><\/p><p><span style=\"font-weight: 400;\">Cependant, il ne s'agit pas seulement d'\u00eatre \u00e0 l'aise avec la technologie, mais aussi de tirer parti de ces outils pour \u00e9laborer des strat\u00e9gies financi\u00e8res plus efficaces et mieux inform\u00e9es. Selon le World Wealth Report, <\/span><a href=\"https:\/\/fintech.global\/2023\/07\/06\/how-wealth-managers-can-revolutionise-decision-making-with-technology\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">plus de 60 % des conseillers financiers n'ont pas acc\u00e8s aux donn\u00e9es et \u00e0 la technologie<\/span><\/a><span style=\"font-weight: 400;\"> qui leur permettraient d'acqu\u00e9rir un avantage concurrentiel en mati\u00e8re d'engagement des clients et de performance des investissements.<\/span><\/p><p><span style=\"font-weight: 400;\">Les gestionnaires de patrimoine devront peut-\u00eatre int\u00e9grer leurs connaissances et leur expertise \u00e0 ces outils, en veillant \u00e0 ce que, tout en s'appuyant sur des donn\u00e9es, ils fassent \u00e9galement appel \u00e0 leur jugement, qui s'est affin\u00e9 au fil des ann\u00e9es d'exp\u00e9rience. Ces plateformes peuvent potentiellement offrir des donn\u00e9es en temps r\u00e9el, des analyses pr\u00e9dictives et m\u00eame des informations bas\u00e9es sur l'IA, permettant aux gestionnaires de patrimoine de prendre des d\u00e9cisions plus strat\u00e9giques.<\/span><\/p><h4><b>Cybers\u00e9curit\u00e9 et protection des donn\u00e9es<\/b><\/h4><p><span style=\"font-weight: 400;\">Dans le monde interconnect\u00e9 d'aujourd'hui, les violations de donn\u00e9es et les cybermenaces sont plus que de simples pr\u00e9occupations techniques. Elles posent des risques financiers consid\u00e9rables, en particulier pour les personnes fortun\u00e9es. Les gestionnaires de patrimoine doivent \u00eatre les gardiens non seulement du patrimoine, mais aussi des donn\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Il est fondamental de comprendre les bases de la cybers\u00e9curit\u00e9, des communications s\u00e9curis\u00e9es \u00e0 l'authentification \u00e0 deux facteurs. Selon un rapport, <\/span><a href=\"https:\/\/onlinedegrees.sandiego.edu\/top-cyber-security-threats\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">une part importante des cyberattaques vise des personnes fortun\u00e9es<\/span><\/a><span style=\"font-weight: 400;\">. Il est donc imp\u00e9ratif que leurs gestionnaires de patrimoine connaissent bien les protocoles et mesures de s\u00e9curit\u00e9 avanc\u00e9s.<\/span><\/p><p><span style=\"font-weight: 400;\">Mais au-del\u00e0 de la mise en \u0153uvre d'outils de s\u00e9curit\u00e9, il s'agit d'encourager une culture de la vigilance. Il peut s'agir d'informer r\u00e9guli\u00e8rement les clients sur les vuln\u00e9rabilit\u00e9s potentielles, de recommander les meilleures pratiques num\u00e9riques, voire de collaborer avec des experts en cybers\u00e9curit\u00e9 pour auditer et renforcer leur infrastructure financi\u00e8re.<\/span><\/p><p><span style=\"font-weight: 400;\">Par essence, le r\u00f4le du gestionnaire de patrimoine moderne est multiple, m\u00ealant les nuances de la finance aux subtilit\u00e9s de la technologie num\u00e9rique. Bien que le paysage financier puisse changer et que le monde num\u00e9rique puisse \u00e9voluer, la responsabilit\u00e9 centrale d'un gestionnaire de patrimoine - prot\u00e9ger et faire fructifier le patrimoine - reste in\u00e9branlable, m\u00eame s'il dispose d'outils modernes.<\/span><\/p><p>\u00a0<\/p><h3><b>La touche humaine dans la gestion de patrimoine num\u00e9rique<\/b><\/h3><p><span style=\"font-weight: 400;\">Alors que le paysage de la gestion de patrimoine entre dans l'\u00e8re num\u00e9rique, il est essentiel de rappeler la valeur irrempla\u00e7able de l'\u00e9l\u00e9ment humain. Les subtilit\u00e9s de la finance ne se limitent pas aux chiffres ; elles sont profond\u00e9ment li\u00e9es aux \u00e9motions, aux aspirations et aux histoires individuelles. Si la technologie change la donne, l'intuition humaine, l'exp\u00e9rience et la touche personnelle restent au c\u0153ur de la gestion de patrimoine.<\/span><\/p><h4><b>La technologie ne peut pas remplacer l'intuition humaine<\/b><\/h4><p><span style=\"font-weight: 400;\">Les outils num\u00e9riques fournissent des donn\u00e9es, des analyses et des informations solides, mais il leur manque l'intuition humaine acquise au fil des ann\u00e9es d'exp\u00e9rience. Comprendre les aspirations, les craintes et les r\u00eaves des clients n'est pas une chose que les algorithmes peuvent appr\u00e9hender pleinement. Les meilleures d\u00e9cisions sont souvent le fruit d'un m\u00e9lange de donn\u00e9es et de jugement humain. En outre, les UHNWI et HNWI recherchent la confiance, la compr\u00e9hension et un lien personnel, des \u00e9l\u00e9ments que les logiciels seuls ne peuvent pas offrir.<\/span><\/p><h4><b>Strat\u00e9gies pour maintenir et am\u00e9liorer les relations avec les clients par voie num\u00e9rique<\/b><\/h4><ul style=\"padding-bottom: 20px;\"><li aria-level=\"1\"><b>Communication num\u00e9rique personnalis\u00e9e :<\/b><span style=\"font-weight: 400;\"> Utiliser la technologie pour adapter les communications, par exemple en envoyant des informations personnalis\u00e9es sur les march\u00e9s ou en cr\u00e9ant des tableaux de bord d'investissement personnalis\u00e9s pour chaque client.<\/span><\/li><li aria-level=\"1\"><b>Contr\u00f4les virtuels r\u00e9guliers :<\/b><span style=\"font-weight: 400;\"> Garantir des interactions en face-\u00e0-face par le biais d'appels vid\u00e9o, ce qui permet de discuter des pr\u00e9occupations, des objectifs et des strat\u00e9gies dans un cadre plus personnel.<\/span><\/li><li aria-level=\"1\"><b>Webinaires \u00e9ducatifs : <\/b><span style=\"font-weight: 400;\">Organiser des \u00e9v\u00e9nements num\u00e9riques pour informer les clients sur les tendances du march\u00e9 et leur offrir des informations pr\u00e9cieuses pour prendre des d\u00e9cisions en connaissance de cause.<\/span><\/li><li aria-level=\"1\"><b>Plateformes interactives : <\/b><span style=\"font-weight: 400;\">L'utilisation de portails clients qui permettent aux clients d'avoir un acc\u00e8s en temps r\u00e9el \u00e0 leurs portefeuilles mais aussi d'entrer en contact et de communiquer avec leurs gestionnaires de patrimoine<\/span><\/li><\/ul><h4><b>Naviguer sur les plateformes num\u00e9riques de gestion de patrimoine<\/b><\/h4><p><span style=\"font-weight: 400;\">La prolif\u00e9ration des plateformes de gestion de patrimoine num\u00e9rique a mis en lumi\u00e8re plusieurs piliers du secteur. Parmi eux, la <\/span><a href=\"https:\/\/altoo.io\/fr\/gestion-de-patrimoine\/\"><span style=\"font-weight: 400;\">Plateforme de Gestion de Patrimoine Altoo<\/span><\/a><span style=\"font-weight: 400;\">, qui associe de mani\u00e8re transparente la technologie \u00e0 l'expertise humaine.<\/span><\/p><p><span style=\"font-weight: 400;\">La plateforme Altoo offre une vue consolid\u00e9e du patrimoine, des actifs tangibles aux investissements, garantissant aux UHNWI et HNWI une vision compl\u00e8te et en temps r\u00e9el \u00e0 port\u00e9e de main. Mais ce qui distingue vraiment Altoo, c'est son \u00e9quipe de professionnels experts. Ils veillent \u00e0 ce que les clients ne re\u00e7oivent pas simplement des donn\u00e9es, mais qu'ils soient guid\u00e9s \u00e0 travers elles, en les aidant \u00e0 les interpr\u00e9ter, \u00e0 les comprendre et \u00e0 agir en cons\u00e9quence.<\/span><\/p><p><span style=\"font-weight: 400;\">De plus, les solutions logicielles d'Altoo sont con\u00e7ues pour l'utilisateur. Des tableaux de bord simplifi\u00e9s, des interfaces intuitives et des fonctions de s\u00e9curit\u00e9 font de la gestion de patrimoine un processus plus rationnel et plus transparent. Ces outils sont susceptibles de r\u00e9volutionner la mani\u00e8re dont les gestionnaires de patrimoine interagissent avec leurs clients, en rendant les interactions plus significatives et plus productives.<\/span><\/p><p><span style=\"font-weight: 400;\">Si la num\u00e9risation de la gestion de patrimoine apporte une commodit\u00e9 et des informations in\u00e9gal\u00e9es, c'est la combinaison de l'expertise humaine et des prouesses technologiques qui garantit les meilleurs r\u00e9sultats. Mettre l'accent sur le contact humain dans ce domaine num\u00e9rique est, et restera, la cl\u00e9 de vo\u00fbte d'une gestion de patrimoine r\u00e9ussie.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Dans un monde de plus en plus dirig\u00e9 par des algorithmes bas\u00e9s sur les donn\u00e9es et la pr\u00e9cision des machines, les Ultra-High-Net-Worth Individuals (UHNWI) et les High-Net-Worth Individuals (HNWI) se trouvent \u00e0 la crois\u00e9e des chemins. Le pouvoir de transformation de la technologie est ind\u00e9niable. Cependant, une \u00e9volution num\u00e9rique aussi rapide s'accompagne de d\u00e9fis, non seulement pour ma\u00eetriser la pl\u00e9thore d'outils technologiques disponibles, mais aussi pour anticiper une s\u00e9rie de cybermenaces en constante \u00e9volution.<\/p>","protected":false},"author":12,"featured_media":24480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[38],"tags":[698],"class_list":["post-24479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wealth-management","tag-digital-age-and-wealth-managers"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/24479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=24479"}],"version-history":[{"count":9,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/24479\/revisions"}],"predecessor-version":[{"id":29669,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/24479\/revisions\/29669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/24480"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=24479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=24479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=24479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}