{"id":18386,"date":"2023-08-22T10:00:18","date_gmt":"2023-08-22T08:00:18","guid":{"rendered":"https:\/\/altoo.io\/?p=18386"},"modified":"2023-08-21T20:00:26","modified_gmt":"2023-08-21T18:00:26","slug":"tuesday_the-adventure-of-luxury-train-jours-2","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/tuesday_the-adventure-of-luxury-train-journeys-2\/","title":{"rendered":"L'Aventure des Voyages en Train de Luxe (2)"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"18386\" class=\"elementor elementor-18386\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f5526b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f5526b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c71a265\" data-id=\"c71a265\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-554dc75 elementor-widget elementor-widget-text-editor\" data-id=\"554dc75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Rocky Mountaineer GoldLeaf Service : Panorama majestueux de la nature<\/b><\/h4><p><span style=\"font-weight: 400;\">Le Rocky Mountaineer du Canada offre une \u00e9chapp\u00e9e luxueuse dans la grandeur de la nature. Avec son service GoldLeaf, ce voyage en train offre des vues panoramiques sur les sommets enneig\u00e9s, les lacs scintillants et les prairies verdoyantes des Rocheuses canadiennes. En vous installant dans votre cabine vitr\u00e9e \u00e0 deux niveaux, vous serez immerg\u00e9 dans le paysage grandiose qui s'offre \u00e0 vos yeux.<\/span><\/p><p><span style=\"font-weight: 400;\">D\u00e9tendez-vous dans des si\u00e8ges moelleux et savourez de d\u00e9licieux repas pr\u00e9par\u00e9s avec des ingr\u00e9dients frais et de saison. Le service attentif veille \u00e0 ce que chaque instant soit une c\u00e9l\u00e9bration du luxe et de la beaut\u00e9 naturelle. Plongez dans la majest\u00e9 des Rocheuses tandis que le train suit les rives de la rivi\u00e8re Thompson Nord, r\u00e9v\u00e9lant les plus hauts sommets et les joyaux cach\u00e9s de cette r\u00e9gion \u00e0 couper le souffle. Le Rocky Mountaineer GoldLeaf Service est une invitation \u00e0 d\u00e9couvrir la splendeur de la nature dans un confort et un style in\u00e9gal\u00e9s.<\/span><\/p><figure id=\"attachment_18390\" aria-describedby=\"caption-attachment-18390\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-18390 size-full\" src=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/rocky-mountaineer.jpg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/rocky-mountaineer.jpg 768w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/rocky-mountaineer-300x200.jpg 300w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/rocky-mountaineer-18x12.jpg 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption id=\"caption-attachment-18390\" class=\"wp-caption-text\">Montagnard des Rocheuses<\/figcaption><\/figure><h4><b>Le Train Bleu : Un passage luxueux \u00e0 travers l'Afrique du Sud<\/b><\/h4><p><span style=\"font-weight: 400;\">Voyagez \u00e0 travers les paysages vari\u00e9s de l'Afrique du Sud \u00e0 bord de l'embl\u00e9matique Train bleu, qui t\u00e9moigne de la riche histoire et de la splendeur naturelle du pays. En service depuis les ann\u00e9es 1920, ce train de luxe l\u00e9gendaire vous invite \u00e0 embarquer pour une odyss\u00e9e de 27 heures et de 1 600 kilom\u00e8tres, de Pretoria au Cap. En traversant des savanes \u00e9tendues et des panoramas \u00e9poustouflants, vous serez immerg\u00e9 dans l'\u00e9l\u00e9gance et le raffinement.<\/span><\/p><p><span style=\"font-weight: 400;\">Entrez dans votre suite luxueuse, orn\u00e9e de sols en marbre et de luminaires en or, et plongez dans une baignoire de grande taille. Laissez-vous tenter par les d\u00e9lices locaux les plus raffin\u00e9s, pr\u00e9par\u00e9s par les meilleurs chefs, accompagn\u00e9s par les m\u00e9lodies \u00e9mouvantes du jazz et de la musique classique. Le Train Bleu offre une fen\u00eatre sur l'\u00e2me de l'Afrique, o\u00f9 opulence et beaut\u00e9 naturelle se m\u00ealent en parfaite harmonie. En voyageant au c\u0153ur de l'Afrique du Sud, vous cr\u00e9erez des souvenirs qui dureront toute votre vie.<\/span><\/p><figure id=\"attachment_18391\" aria-describedby=\"caption-attachment-18391\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-18391 size-full\" src=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/blue-train1.jpg\" alt=\"Le train bleu, Source:bluetrain.co.za \" width=\"768\" height=\"512\" srcset=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/blue-train1.jpg 768w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/blue-train1-300x200.jpg 300w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/blue-train1-18x12.jpg 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption id=\"caption-attachment-18391\" class=\"wp-caption-text\">Le train bleu, Source:bluetrain.co.za<\/figcaption><\/figure><h4><b>L'exp\u00e9dition Ghan : Une aventure en Australie<\/b><\/h4><p><span style=\"font-weight: 400;\">D\u00e9couvrez la beaut\u00e9 sauvage de l'Outback australien lors de la Ghan Expedition, un voyage en train renomm\u00e9 qui traverse les vastes paysages d'Ad\u00e9la\u00efde \u00e0 Darwin. Cette aventure de trois nuits et quatre jours offre une exp\u00e9rience immersive dans l'une des r\u00e9gions les plus captivantes du monde.<\/span><\/p><p><span style=\"font-weight: 400;\">Au cours de votre voyage \u00e0 travers la terre rouge br\u00fbl\u00e9e et le terrain accident\u00e9, vous serez envelopp\u00e9 dans le confort et le luxe des \u00e9l\u00e9gantes cabines et des voitures-restaurants exclusives du Ghan. Savourez des repas gastronomiques pr\u00e9par\u00e9s avec des ingr\u00e9dients r\u00e9gionaux, comme le filet de kangourou grill\u00e9 et le barramundi, accompagn\u00e9s des meilleurs vins australiens. Admirez l'\u00e9poustouflante Voie lact\u00e9e en vous relaxant dans l'aire d'observation ext\u00e9rieure et en regardant le ciel \u00e9toil\u00e9.<\/span><\/p><p><span style=\"font-weight: 400;\">Avec des arr\u00eats \u00e0 Coober Pedy, Katherine et Alice Springs, l'exp\u00e9dition Ghan propose des excursions uniques \u00e0 Uluru et dans une ferme d'\u00e9levage, ce qui permet de mieux comprendre le riche patrimoine culturel de l'Outback. Plongez dans l'esprit d'aventure en traversant ce paysage australien embl\u00e9matique dans un style in\u00e9gal\u00e9.<\/span><\/p><figure id=\"attachment_18392\" aria-describedby=\"caption-attachment-18392\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-18392 size-full\" src=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/ghan-expedition.jpg\" alt=\"Le train du Ghan\" width=\"768\" height=\"512\" srcset=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/ghan-expedition.jpg 768w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/ghan-expedition-300x200.jpg 300w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/08\/ghan-expedition-18x12.jpg 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption id=\"caption-attachment-18392\" class=\"wp-caption-text\">Le train du Ghan<\/figcaption><\/figure>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Entrez dans le royaume des voyages en train extraordinaires, o\u00f9 la danse rythmique des roues sur les rails constitue la toile de fond d'une exp\u00e9dition de luxe in\u00e9gal\u00e9e. Du Rocky Mountaineer canadien aux itin\u00e9raires exotiques d'Afrique du Sud, rejoignez-nous pour vivre certaines des aventures ferroviaires les plus somptueuses au monde, m\u00ealant harmonieusement le plaisir et le frisson.<\/p>","protected":false},"author":12,"featured_media":18387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[57,72],"tags":[471],"class_list":["post-18386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifestyle","category-travel","tag-adventure-of-luxury-train"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/18386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=18386"}],"version-history":[{"count":25,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/18386\/revisions"}],"predecessor-version":[{"id":18595,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/18386\/revisions\/18595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/18387"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=18386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=18386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=18386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}