{"id":17366,"date":"2023-08-10T10:00:16","date_gmt":"2023-08-10T08:00:16","guid":{"rendered":"https:\/\/altoo.io\/?p=17366"},"modified":"2026-02-09T18:25:01","modified_gmt":"2026-02-09T17:25:01","slug":"lhistoire-des-banques-privees-suisses","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/the-history-of-swiss-private-banks\/","title":{"rendered":"L'Histoire des Banques Priv\u00e9es Suisses"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"17366\" class=\"elementor elementor-17366\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3d88fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3d88fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d94c70a\" data-id=\"d94c70a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f4605b elementor-widget elementor-widget-text-editor\" data-id=\"2f4605b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Les si\u00e8cles de commerce en Suisse\u00a0<\/b><\/h4><p><span style=\"font-weight: 400;\">Situ\u00e9e au centre de l'Europe, avec un acc\u00e8s \u00e0 d'importants passages alpins, \u00e0 de nombreux pays communs et au Rhin, la Suisse a acquis un r\u00f4le important en tant que centre commercial au Moyen \u00c2ge.<\/span><\/p><p><span style=\"font-weight: 400;\">Au XVe si\u00e8cle, les foires de Gen\u00e8ve, tr\u00e8s florissantes, attiraient les investisseurs \u00e9trangers. Les foires \u00e9taient un \u00e9l\u00e9ment important de la sc\u00e8ne commerciale m\u00e9di\u00e9vale en Europe. Youssef Cassis, professeur d'histoire \u00e9conomique \u00e0 l'Institut europ\u00e9en d'enseignement sup\u00e9rieur de Toscane, explique que la Suisse a rendu son secteur bancaire fortement d\u00e9pendant des marchands et des experts financiers \u00e9trangers.<\/span><\/p><p><span style=\"font-weight: 400;\">Au XVIIe si\u00e8cle, la Suisse a \u00e9t\u00e9 un important refuge pour les r\u00e9fugi\u00e9s protestants des pays catholiques voisins, ce qui a \u00e9galement contribu\u00e9 \u00e0 la croissance du secteur bancaire. En raison de l'afflux d'\u00e9migrants, la Suisse a accueilli non seulement des horlogers, mais aussi des professionnels de la banque et d'autres travailleurs qualifi\u00e9s.<\/span><\/p><p><span style=\"font-weight: 400;\">Selon Cassis, toutes les banques d'Europe et de Suisse \u00e9taient \u00e0 l'origine des soci\u00e9t\u00e9s commerciales sp\u00e9cialis\u00e9es dans le financement des transactions commerciales, mais lorsque la banque est devenue une profession ind\u00e9pendante, elles ont fusionn\u00e9. La banque priv\u00e9e s'est d\u00e9velopp\u00e9e \u00e0 partir du monde traditionnel des banquiers priv\u00e9s, qui sont d\u00e9finis comme des soci\u00e9t\u00e9s priv\u00e9es et assument une responsabilit\u00e9 illimit\u00e9e en cas de pertes.<\/span><\/p><h4><b>Banques et neutralit\u00e9 de la Suisse\u00a0<\/b><\/h4><p><span style=\"font-weight: 400;\">Au fur et \u00e0 mesure que les entreprises de Gen\u00e8ve, de B\u00e2le et, plus tard, les g\u00e9ants du textile de Saint-Gall se d\u00e9veloppaient, ils avaient besoin d'experts financiers qui s'int\u00e9ressaient aux pr\u00eats, aux devises et aux premiers produits d\u00e9riv\u00e9s destin\u00e9s \u00e0 compenser les risques commerciaux.<\/span><\/p><p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 ce succ\u00e8s, certains des noms les plus c\u00e9l\u00e8bres du secteur bancaire priv\u00e9 suisse ont \u00e9t\u00e9 fond\u00e9s par la suite, notamment Lombard Odier Darier Hentsch (1796), Pictet (1805), Mirabaud (1819) et Bordier. (1844).<\/span><\/p><p><span style=\"font-weight: 400;\">La reconnaissance de la neutralit\u00e9 politique de la Suisse en 1815 et la cr\u00e9ation de l'\u00c9tat f\u00e9d\u00e9ral moderne \u00e0 la suite de la guerre civile de 1847 ont contribu\u00e9 \u00e0 l'\u00e9tablissement d'un solide secteur de la gestion de patrimoine.<\/span><\/p><p><span style=\"font-weight: 400;\">Selon l'historien \u00e9conomique suisse Robert Vogler, les anciennes monarchies r\u00e9actionnaires qui entouraient la Suisse offraient un environnement politique et \u00e9conomique id\u00e9al pour le stockage s\u00e9curis\u00e9 des actifs. Toutefois, les graves troubles politiques et \u00e9conomiques du XXe si\u00e8cle ont eu un impact sur la Suisse. Elle s'est \u00e9tablie \u00e0 l'avant-garde de la banque priv\u00e9e internationale. Les actifs ont \u00e9t\u00e9 attir\u00e9s vers la Suisse comme un aimant par les deux guerres mondiales, la guerre froide, les crises financi\u00e8res et l'instabilit\u00e9 de nombreuses autres monnaies.<\/span><\/p><p><span style=\"font-weight: 400;\">L'ancrage du secret bancaire dans le droit national entre les deux guerres mondiales et l'attrait de la Suisse pour les grandes sommes d'argent, qui ne pouvaient \u00eatre r\u00e9alis\u00e9es en raison des restrictions europ\u00e9ennes sur les \u00e9changes de devises entre les pays, ont \u00e9t\u00e9 les raisons de l'augmentation de la gestion d'actifs en Suisse. La stabilit\u00e9 et l'\u00e9change du franc suisse contre d'autres monnaies en p\u00e9riode de volatilit\u00e9 \u00e9conomique dans le monde ont \u00e9galement renforc\u00e9 l'attrait de la Suisse en tant que lieu de gestion d'actifs.<\/span><\/p><h4><b>Les d\u00e9fis du 21e si\u00e8cle<\/b><\/h4><p><span style=\"font-weight: 400;\">Apr\u00e8s l'ann\u00e9e record de 2021, les actifs g\u00e9r\u00e9s par les banques priv\u00e9es en Suisse en 2022 ont diminu\u00e9 de 361 milliards de francs suisses, passant d'environ 3,3 \u00e0 environ 2,9 billions de francs suisses, ce qui correspond \u00e0 une diminution d'environ 11%. Cette \u00e9volution est due \u00e0 une baisse de l'afflux net d'argent frais et, en particulier, aux mauvaises performances des march\u00e9s financiers en raison de l'augmentation des incertitudes g\u00e9opolitiques et macro\u00e9conomiques.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>L'histoire des banques priv\u00e9es suisses remonte \u00e0 plus de 250 ans. Gr\u00e2ce \u00e0 sa situation g\u00e9ographique optimale, \u00e0 ses bonnes relations avec les autres r\u00e9gions et \u00e0 sa neutralit\u00e9, un syst\u00e8me bancaire stable s'est mis en place au cours des si\u00e8cles pass\u00e9s.<\/p>","protected":false},"author":12,"featured_media":17367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,85],"tags":[619],"class_list":["post-17366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-switzerland","tag-private-banking"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/17366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=17366"}],"version-history":[{"count":9,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/17366\/revisions"}],"predecessor-version":[{"id":17426,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/17366\/revisions\/17426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/17367"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=17366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=17366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=17366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}