{"id":17048,"date":"2023-08-07T10:00:22","date_gmt":"2023-08-07T08:00:22","guid":{"rendered":"https:\/\/altoo.io\/?p=17048"},"modified":"2023-08-06T14:33:56","modified_gmt":"2023-08-06T12:33:56","slug":"catherine-ashton-en-un-portrait","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/catherine-ashton-in-a-portrait\/","title":{"rendered":"Catherine Ashton dans un portrait"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"17048\" class=\"elementor elementor-17048\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bc1230 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bc1230\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a918b7\" data-id=\"0a918b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58d8039 elementor-widget elementor-widget-text-editor\" data-id=\"58d8039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Le chemin vers la politique<\/b><\/h4><p><span style=\"font-weight: 400\">Au Bedford College, Ashton a \u00e9tudi\u00e9 l'\u00e9conomie et a obtenu en 1977 une licence en sociologie. Avant d'accepter un emploi dans le conseil en gestion en 1979, elle a travaill\u00e9 comme secr\u00e9taire pour la Campagne pour le d\u00e9sarmement nucl\u00e9aire apr\u00e8s l'obtention de son dipl\u00f4me. De 1983 \u00e0 1989, Mme Ashton a \u00e9t\u00e9 directrice de Business in the Community, un groupe qui promeut la responsabilit\u00e9 sociale des entreprises et soutient la coop\u00e9ration entre les secteurs public et priv\u00e9. Dans les ann\u00e9es 1990, elle a travaill\u00e9 comme conseill\u00e8re politique jusqu'\u00e0 ce qu'elle soit \u00e9lue \u00e0 la t\u00eate de l'autorit\u00e9 sanitaire du Hertfordshire en 1998. En tant que baronne Ashton of Upholland, originaire de St Albans dans le Hertfordshire, elle a \u00e9t\u00e9 \u00e9lue \u00e0 la Chambre des Lords l'ann\u00e9e suivante, apr\u00e8s avoir \u00e9t\u00e9 \u00e9lev\u00e9e \u00e0 la pairie \u00e0 vie par le Premier ministre Tony Blair.<\/span><\/p><h4><b>Questions relatives aux droits de l'homme<\/b><\/h4><p><span style=\"font-weight: 400\">Tout au long de sa carri\u00e8re parlementaire, elle s'est concentr\u00e9e sur les questions d'\u00e9ducation et de droits de l'homme. De 2001 \u00e0 2004, elle a occup\u00e9 le poste de secr\u00e9taire d'\u00c9tat au minist\u00e8re de l'\u00e9ducation et, en 2002, elle a pris la t\u00eate de l'initiative d'apprentissage pr\u00e9coce Sure Start. Mme Ashton a \u00e9galement occup\u00e9 le poste de secr\u00e9taire d'\u00c9tat aux affaires constitutionnelles en 2004. Elle a \u00e9t\u00e9 nomm\u00e9e au Conseil priv\u00e9 en mai 2006 et, la m\u00eame ann\u00e9e, l'organisation de d\u00e9fense des droits des gays et lesbiennes Stonewall lui a d\u00e9cern\u00e9 le titre de personnalit\u00e9 politique de l'ann\u00e9e pour ses efforts en faveur de l'\u00e9galit\u00e9. En 2007, elle a \u00e9t\u00e9 promue Leader de la Chambre des Lords par le Premier ministre Gordon Brown. Elle a jou\u00e9 un r\u00f4le important en facilitant l'adoption du trait\u00e9 de Lisbonne par la Chambre des Lords. L'ann\u00e9e suivante, elle a \u00e9t\u00e9 nomm\u00e9e commissaire au commerce au sein de la Commission europ\u00e9enne.<\/span><\/p><h4><b>M\u00e9diateur efficace dans les situations de crise<\/b><\/h4><p><span style=\"font-weight: 400\">Dans les premiers jours de son mandat, Mme Ashton a \u00e9t\u00e9 critiqu\u00e9e pour avoir d\u00fb d\u00e9finir son r\u00f4le au sein de la bureaucratie de l'UE, en particulier par rapport \u00e0 M. Barroso et \u00e0 la Commission europ\u00e9enne. Ses d\u00e9tracteurs ont \u00e9galement critiqu\u00e9 ce qu'ils consid\u00e8rent comme la lenteur de sa r\u00e9action aux \u00e9v\u00e9nements du printemps arabe en 2010-2011. Le Service europ\u00e9en pour l'action ext\u00e9rieure (SEAE), le bras diplomatique de l'UE, a \u00e9t\u00e9 cr\u00e9\u00e9 en 2011, et les politiciens eurosceptiques et les professionnels du Service pour l'action ext\u00e9rieure ont remis en question \u00e0 la fois les objectifs de l'organisation et le leadership de Mme Ashton. Toutefois, au fil du temps, Mme Ashton s'est r\u00e9v\u00e9l\u00e9e tr\u00e8s efficace pour repr\u00e9senter les objectifs parfois contradictoires des 28 membres de l'UE. Elle a men\u00e9 des n\u00e9gociations entre les dirigeants de la Serbie et du Kosovo pendant deux ans, qui se sont conclues en 2013 par un accord historique de normalisation des relations entre les deux pays. Elle a \u00e9galement facilit\u00e9 les n\u00e9gociations bipartites sur le programme nucl\u00e9aire iranien. Apr\u00e8s l'expiration de son mandat en 2014, il lui a \u00e9t\u00e9 demand\u00e9 de continuer \u00e0 coordonner les pourparlers, son implication personnelle dans ces n\u00e9gociations \u00e9tant consid\u00e9r\u00e9e comme tr\u00e8s importante.<\/span><\/p><p><span style=\"font-weight: 400\">En janvier 2017, Mme Ashton a pris ses fonctions de chanceli\u00e8re de l'universit\u00e9 de Warwick en remplacement de Sir Richard Lambert. Elle est ainsi la premi\u00e8re femme chanceli\u00e8re de l'universit\u00e9 de Warwick.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Catherine Ashton contribue \u00e0 l'expertise g\u00e9opolitique d'Eurasia Group dans l'UE, au Royaume-Uni et dans le monde gr\u00e2ce \u00e0 sa longue exp\u00e9rience en mati\u00e8re de politique \u00e9trang\u00e8re, de diplomatie et de commerce.<\/p>","protected":false},"author":12,"featured_media":17049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[73,69,57,84],"tags":[415],"class_list":["post-17048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-explore-by-topic","category-art-and-culture","category-lifestyle","category-women","tag-catherine-ashton"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/17048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=17048"}],"version-history":[{"count":12,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/17048\/revisions"}],"predecessor-version":[{"id":17092,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/17048\/revisions\/17092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/17049"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=17048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=17048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=17048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}