{"id":16740,"date":"2023-08-02T10:00:02","date_gmt":"2023-08-02T08:00:02","guid":{"rendered":"https:\/\/altoo.io\/?p=16740"},"modified":"2023-08-01T19:12:09","modified_gmt":"2023-08-01T17:12:09","slug":"la-pollution-lumineuse-et-ses-consequences","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/light-pollution-and-its-consequences\/","title":{"rendered":"La Pollution Lumineuse et Ses Cons\u00e9quences"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16740\" class=\"elementor elementor-16740\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f93ed8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f93ed8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-484fbbe\" data-id=\"484fbbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04daec1 elementor-widget elementor-widget-text-editor\" data-id=\"04daec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Nuits lumineuses<\/b><\/h4><p><span style=\"font-weight: 400;\">L'Atlas mondial de la pollution lumineuse, publi\u00e9 par une \u00e9quipe internationale de scientifiques, montre \u00e0 quel point l'\u00e9clairage artificiel illumine le ciel nocturne dans le monde entier. En 2016 d\u00e9j\u00e0, plus de 80 % de la population mondiale vivait sous un ciel pollu\u00e9 par la lumi\u00e8re. M\u00eame 99 % des habitants de l'Europe et des \u00c9tats-Unis sont concern\u00e9s. Rien qu'en Allemagne, par exemple, pr\u00e8s de la moiti\u00e9 des personnes de moins de 30 ans d\u00e9clarent n'avoir jamais vu la Voie lact\u00e9e dans le ciel nocturne.<\/span><\/p><h4><b>Les animaux et les plantes souffrent du smog l\u00e9ger\u00a0<\/b><\/h4><p><span style=\"font-weight: 400;\">L'\u00e9clairage permanent de nos villes emp\u00eache \u00e9galement la bonne r\u00e9g\u00e9n\u00e9ration des animaux. De nombreux insectes et oiseaux sont actifs la nuit et sont perturb\u00e9s dans leur rythme ou leur orientation. Le smog lumineux perturbe les \u00e9cosyst\u00e8mes, comme les tortues de mer nouvellement \u00e9closes qui courent vers la ville \u00e9clair\u00e9e au lieu de la mer. Les c\u00f4nes de lumi\u00e8re induisent en erreur les oiseaux migrateurs qui ne s'orientent pas en fonction de la lumi\u00e8re de la Voie lact\u00e9e. Autre exemple : Par une nuit d'\u00e9t\u00e9, un lampadaire peut avoir 150 insectes sur sa conscience, et il y a environ 7 millions de lampadaires rien qu'en Allemagne. L'\u00e9clairage artificiel constitue donc un d\u00e9fi dans le contexte du probl\u00e8me complexe de la mortalit\u00e9 des oiseaux et des insectes.<\/span><\/p><p><span style=\"font-weight: 400;\">M\u00eame les plantes ont besoin d'obscurit\u00e9 pour se remettre de la photosynth\u00e8se et r\u00e9parer les feuilles et les tiges cass\u00e9es. En outre, les plantes \u00e9clair\u00e9es en permanence ont moins de chances d'\u00eatre pollinis\u00e9es et produisent donc moins de fruits. Elles ratent l'automne et le printemps en perdant leurs feuilles trop tard ou en d\u00e9veloppant de nouvelles pousses trop t\u00f4t. Cela perturbe \u00e9galement leur biorythme \u00e0 long terme.<\/span><b>\u00a0<\/b><\/p><h4><b>Effets sur la sant\u00e9 des personnes<\/b><\/h4><p><span style=\"font-weight: 400;\">Un exc\u00e8s de lumi\u00e8re peut \u00e9galement nous rendre malades \u00e0 long terme. La lumi\u00e8re bleue et froide des diodes \u00e9lectroluminescentes des enseignes au n\u00e9on et de l'\u00e9clairage public moderne, ainsi que des t\u00e9l\u00e9viseurs, des t\u00e9l\u00e9phones mobiles et des ordinateurs portables, a le m\u00eame effet sur nous que la lumi\u00e8re du jour et nous maintient \u00e9veill\u00e9s. Ce n'est que dans l'obscurit\u00e9 que notre corps produit l'hormone du sommeil, la m\u00e9latonine, qui r\u00e9gule notre rythme entre le jour et la nuit, comme le font les vert\u00e9br\u00e9s. La lumi\u00e8re inhibe la production de m\u00e9latonine. Sans l'obscurit\u00e9, nous vivrions \u00e0 contre-courant de notre horloge interne et dormirions trop peu. Les cellules ne se r\u00e9g\u00e9n\u00e8rent pas suffisamment et la personne ne peut pas r\u00e9cup\u00e9rer suffisamment. Trop de lumi\u00e8re la nuit peut entra\u00eener des troubles du sommeil \u00e0 long terme et, en cons\u00e9quence, d'autres probl\u00e8mes de sant\u00e9.<\/span><\/p><p><span style=\"font-weight: 400;\">Les \u00e9cosyst\u00e8mes et les processus naturels affect\u00e9s par la pollution lumineuse sont nombreux et ne peuvent \u00eatre tous r\u00e9pertori\u00e9s. En outre, les effets de la pollution lumineuse sont tellement complexes et multicouches que les \u00e9tudes actuelles sont encore tr\u00e8s r\u00e9centes et ne fournissent parfois pas de r\u00e9sultats clairs et facilement interpr\u00e9tables. Quoi qu'il en soit, la pollution lumineuse a un effet et un impact \u00e9normes sur les \u00e9cosyst\u00e8mes, et ce que l'on sait jusqu'\u00e0 pr\u00e9sent est essentiellement n\u00e9gatif.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Lorsque vous levez les yeux le soir, vous ne pouvez voir un ciel \u00e9toil\u00e9 qu'en de rares endroits. En effet, la pollution lumineuse contamine fr\u00e9quemment la nuit. Le smog lumineux affecte non seulement l'\u00e9clipse et les \u00e9cosyst\u00e8mes, mais aussi nous-m\u00eames. Mais qu'est-ce que cela signifie exactement pour nous et notre environnement ?<\/p>","protected":false},"author":12,"featured_media":16741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[56,73,66,75],"tags":[386,385],"class_list":["post-16740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beyond-markets","category-explore-by-topic","category-megatrends","category-sustainability","tag-consequences","tag-light-pollution"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/16740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=16740"}],"version-history":[{"count":11,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/16740\/revisions"}],"predecessor-version":[{"id":16788,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/16740\/revisions\/16788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/16741"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=16740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=16740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=16740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}