{"id":13630,"date":"2023-07-05T10:00:39","date_gmt":"2023-07-05T08:00:39","guid":{"rendered":"https:\/\/altoo.io\/?p=13630"},"modified":"2023-07-05T10:12:49","modified_gmt":"2023-07-05T08:12:49","slug":"women-in-focus-quest-ce-que-le-gender-lens-wealth-et-pourquoi-devrions-nous-nous-en-preoccuper","status":"publish","type":"post","link":"https:\/\/altoo.io\/fr\/women-in-focus-what-is-gender-lens-wealth-and-why-should-we-care\/","title":{"rendered":"Zoom sur les femmes : Qu'est-ce que la richesse \u00e0 lentille de genre et pourquoi devrions-nous nous en pr\u00e9occuper ?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"13630\" class=\"elementor elementor-13630\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d699b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d699b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24e0931\" data-id=\"24e0931\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-220c408 elementor-widget elementor-widget-text-editor\" data-id=\"220c408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>L'\u00e9galit\u00e9 des sexes dans le cadre des objectifs de d\u00e9veloppement<\/b><\/h4><p><span style=\"font-weight: 400;\">La majorit\u00e9 des pays du monde ont encore des probl\u00e8mes dans le domaine de l'\u00e9galit\u00e9 des femmes. Ce foss\u00e9 qui subsiste entre les sexes a un impact significatif sur les individus, les groupes et la soci\u00e9t\u00e9 dans son ensemble. L'in\u00e9galit\u00e9 des sexes en termes de richesse n'a pas \u00e9t\u00e9 largement \u00e9tudi\u00e9e ou mise au jour, malgr\u00e9 l'attention croissante port\u00e9e par les chefs d'entreprise \u00e0 la diversit\u00e9, \u00e0 l'\u00e9quit\u00e9 et \u00e0 l'inclusion (DEI).<\/span><\/p><p><span style=\"font-weight: 400;\">C'est pourquoi le cinqui\u00e8me des 17 objectifs de d\u00e9veloppement durable (ODD) des Nations unies pour 2030 est l'\u00e9galit\u00e9 des sexes et l'autonomisation des femmes. Cependant, selon un r\u00e9cent rapport du Forum \u00e9conomique mondial, il pourrait falloir 83 ans pour \u00e9liminer les \u00e9carts fondamentaux entre les sexes dans le monde entier. La richesse de genre - la mobilisation de la richesse priv\u00e9e pour l'\u00e9galit\u00e9 des sexes dans le monde - pourrait \u00eatre une force majeure de changement.<\/span><\/p><h4><b>Il faut encore agir<\/b><\/h4><p><span style=\"font-weight: 400;\">Le Forum \u00e9conomique mondial indique qu'au niveau mondial, les femmes n'ont que 59% des opportunit\u00e9s \u00e9conomiques et des taux de participation dont b\u00e9n\u00e9ficient leurs homologues masculins. La protection juridique des femmes reste \u00e9galement insuffisante. Par cons\u00e9quent, dans certains pays, les femmes n'ont qu'un acc\u00e8s limit\u00e9 \u00e0 la terre, aux services financiers ou \u00e0 l'h\u00e9ritage. Par exemple, une \u00e9tude r\u00e9alis\u00e9e par Willis Towers Watson a r\u00e9v\u00e9l\u00e9 que les femmes ne disposeront probablement que de 74% de la richesse des hommes \u00e0 la fin de leur carri\u00e8re. Bien que les march\u00e9s et les lieux soient tr\u00e8s diff\u00e9rents, les causes de l'\u00e9cart de richesse restent ind\u00e9pendantes des cultures, des structures sociales et des infrastructures \u00e9tudi\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Les \u00e9carts salariaux entre les hommes et les femmes, les retards dans le d\u00e9roulement des carri\u00e8res, les responsabilit\u00e9s familiales (par exemple, s'occuper des enfants et des personnes \u00e2g\u00e9es) et les diff\u00e9rences de connaissances financi\u00e8res sont quelques-uns des principaux facteurs \u00e0 l'origine des \u00e9carts de richesse entre les hommes et les femmes.<\/span><\/p><p><span style=\"font-weight: 400;\">Il existe de nombreuses fa\u00e7ons de parvenir \u00e0 l'\u00e9galit\u00e9 entre les hommes et les femmes, mais cela n\u00e9cessite un effort concert\u00e9 et cibl\u00e9 de la part des parties prenantes priv\u00e9es et publiques, y compris non seulement les employeurs, mais aussi les gouvernements, les institutions publiques, la soci\u00e9t\u00e9 dans son ensemble et les individus.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>En savoir plus sur les efforts d\u00e9ploy\u00e9s pour promouvoir l'\u00e9galit\u00e9 entre les hommes et les femmes, sur le concept de \"gender-lens wealth\" et sur l'investissement socialement responsable.<\/p>","protected":false},"author":12,"featured_media":13631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,56,73,66,75,84],"tags":[192],"class_list":["post-13630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-beyond-markets","category-explore-by-topic","category-megatrends","category-sustainability","category-women","tag-female-wealth"],"_links":{"self":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/13630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/comments?post=13630"}],"version-history":[{"count":6,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/13630\/revisions"}],"predecessor-version":[{"id":13754,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/posts\/13630\/revisions\/13754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media\/13631"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/media?parent=13630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/categories?post=13630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/fr\/wp-json\/wp\/v2\/tags?post=13630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}