{"id":41288,"date":"2025-10-07T08:00:18","date_gmt":"2025-10-07T06:00:18","guid":{"rendered":"https:\/\/altoo.io\/?p=41288"},"modified":"2026-02-09T10:32:06","modified_gmt":"2026-02-09T09:32:06","slug":"in-the-know-family-offices-halten-esg-trotz-politischem-druck-am-leben","status":"publish","type":"post","link":"https:\/\/altoo.io\/de\/in-the-know-family-offices-keep-esg-alive-despite-political-pushback\/","title":{"rendered":"Auf dem Laufenden: Family Offices halten ESG trotz politischer Gegenwehr am Leben"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"41288\" class=\"elementor elementor-41288\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ded3aca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ded3aca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a537dd0\" data-id=\"a537dd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2524e45 elementor-widget elementor-widget-heading\" data-id=\"2524e45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Politische Turbulenzen und Marktsignale<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28b9377 elementor-widget elementor-widget-text-editor\" data-id=\"28b9377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Die Zahlen f\u00fcr das erste Quartal 2025 geben die Stimmung in Amerika wieder. <\/span><b>Weltweit verzeichneten nachhaltige Fonds Nettoabfl\u00fcsse in H\u00f6he von $8,6 Mrd. USD, wobei allein aus US-Fonds $6,1 Mrd. USD abgezogen wurden (Reuters, 2025). <\/b><span style=\"font-weight: 400;\">Dies war das zehnte Quartal in Folge mit einem R\u00fcckgang in Amerika. Das gleiche Muster ist auf dem Anleihemarkt zu beobachten. Die Emission gr\u00fcner Anleihen in den USA ging bis Mai 2025 auf $24,4 Mrd. US zur\u00fcck, gegen\u00fcber $43,3 Mrd. US im gleichen Zeitraum des Vorjahres (Financial Times, 2025).<\/span><\/p><p><span style=\"font-weight: 400;\">Diese Trends zeigen, wie politische Ma\u00dfnahmen das kurzfristige Anlegerverhalten beeinflussen k\u00f6nnen. Republikanische Staatsregierungen haben Klagen gegen ESG-Fonds eingereicht und die Zuteilung von Pensionsgeldern an diese Fonds eingeschr\u00e4nkt. Fondsmanager haben ESG-Produkte vermieden, indem sie sie aus Angst vor Klagen umbenannt oder aufgel\u00f6st haben. Auf Unternehmensebene setzen die Firmen ihre Nachhaltigkeitsarbeit im Stillen fort, eine Praxis, die als Greenhushing bekannt ist. HSBC und Bayer zum Beispiel haben ihre Netto-Null-Ziele beibehalten, w\u00e4hrend sie die ESG-Rhetorik abgeschw\u00e4cht haben (Financial Times, 2025).<\/span><span style=\"font-weight: 400;\"><br \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fff49d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fff49d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-132d15a\" data-id=\"132d15a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f197475 elementor-widget elementor-widget-heading\" data-id=\"f197475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">M\u00e4rkte ziehen in eine andere Richtung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6af9251 elementor-widget elementor-widget-text-editor\" data-id=\"6af9251\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>W\u00e4hrend die Politik die Schlagzeilen beherrscht, folgen die M\u00e4rkte den Renditen.<\/b><span style=\"font-weight: 400;\"> Saubere Energie ist jetzt eine eigenst\u00e4ndige Industrie. W\u00e4hrend Trumps erster Amtszeit wurden die staatlichen Anreize f\u00fcr erneuerbare Energien abgeschw\u00e4cht. Dennoch stiegen die Solarinstallationen in den USA zwischen 2016 und 2020 um 50 Prozent, unterst\u00fctzt durch sinkende Technologiekosten und staatliche Subventionen (MarketWatch, 2025).<\/span><\/p><p><span style=\"font-weight: 400;\">Die Internationale Energieagentur (2024) berichtet, dass die weltweiten Investitionen in saubere Energien im Jahr 2024 fast doppelt so hoch waren wie die Investitionen in fossile Brennstoffe. Rund $2 Billionen US-Dollar flossen in erneuerbare Energien, Batterien und Netzausbau, verglichen mit $1 Billionen US-Dollar in Kohlenwasserstoffe. Die Gesamtinvestitionen in den Energiesektor erreichten zum ersten Mal mehr als $3 Billionen US-Dollar. Die Richtung dieses Trends l\u00e4sst sich nur schwer umkehren. Ganz gleich, wer politisch das Sagen hat.<\/span><\/p><p><span style=\"font-weight: 400;\">Die Performance-Daten belegen dies. Ein fiktiver Betrag von $100 US-Dollar, der Ende 2018 in einen nachhaltigen Aktienfonds investiert wurde, ist heute $136 US-Dollar wert, verglichen mit $131 US-Dollar in einem herk\u00f6mmlichen Portfolio (Rothschild &amp; Co, 2025). Anfang 2025 stiegen nachhaltige Large-Cap-Fonds um 2,09 Prozent, w\u00e4hrend der MSCI ACWI-Index um 1,58 Prozent fiel.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d752412 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d752412\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c300d4\" data-id=\"5c300d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90a58c3 elementor-widget elementor-widget-heading\" data-id=\"90a58c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Warum sich Family Offices abheben<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7dd261 elementor-widget elementor-widget-text-editor\" data-id=\"c7dd261\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Family Offices sind anders strukturiert als Verm\u00f6gensverwalter oder Pensionsfonds. Sie verwalten in der Regel das Verm\u00f6gen einer Familie, oft \u00fcber Generationen hinweg. Sie sind nicht an die viertelj\u00e4hrlichen Berichtszyklen oder den Druck der Aktion\u00e4re gebunden. Stattdessen sind sie darauf ausgerichtet, Verm\u00f6gen \u00fcber Jahrzehnte, manchmal Jahrhunderte, zu erhalten und zu vermehren.<\/span><\/p><p><b>Diese strukturelle Unabh\u00e4ngigkeit ver\u00e4ndert den Investitionshorizont. <\/b><span style=\"font-weight: 400;\">Geduldiges Kapital erm\u00f6glicht es Family Offices, illiquide Verm\u00f6genswerte wie privates Beteiligungskapital in erneuerbaren Energien, nachhaltiger Landwirtschaft oder naturbasierten Kohlenstoffprojekten zu halten. Sie k\u00f6nnen politische oder Marktschwankungen aushalten, weil ihr Auftrag nicht kurzfristiger Profit, sondern langfristige Kontinuit\u00e4t ist.<\/span><\/p><p><span style=\"font-weight: 400;\">UBS's <\/span><i><span style=\"font-weight: 400;\">Global Family Office Bericht<\/span><\/i><span style=\"font-weight: 400;\"> (2024) unterstreicht diese Dynamik. Fast die H\u00e4lfte der Family Offices z\u00e4hlt den Klimawandel neben geopolitischer Instabilit\u00e4t zu ihren f\u00fcnf gr\u00f6\u00dften Risiken. Die Studie von UBS <\/span><i><span style=\"font-weight: 400;\">Family Office Quarterly<\/span><\/i><span style=\"font-weight: 400;\"> (2025) geht noch weiter und stellt fest, dass 80 Prozent der B\u00fcros heute neben den Verm\u00f6gensportfolios auch die Betriebsgesellschaften koordinieren. Diese Integration bedeutet, dass Nachhaltigkeitsverpflichtungen oft nicht nur f\u00fcr Investitionen, sondern auch f\u00fcr die Unternehmen im Besitz von Familien gelten.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2c968d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2c968d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b5ce16\" data-id=\"1b5ce16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58a161c elementor-widget elementor-widget-heading\" data-id=\"58a161c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Governance und treuh\u00e4nderische Verantwortung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2073de elementor-widget elementor-widget-text-editor\" data-id=\"b2073de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Auch die Governance spielt eine entscheidende Rolle.<\/b><span style=\"font-weight: 400;\"> Die Vereinten Nationen <\/span><i><span style=\"font-weight: 400;\">Grunds\u00e4tze f\u00fcr verantwortungsvolle Investitionen<\/span><\/i><span style=\"font-weight: 400;\"> argumentieren, dass das Ignorieren von ESG auf eine Verletzung der Treuepflicht hinauslaufen kann (PRI, 2006). Wissenschaftliche Arbeiten unterst\u00fctzen dies. Oprean-Stan (2025) schl\u00e4gt ein Modell des \"nachhaltigen wirtschaftlichen Wertes\" vor, um zu quantifizieren, wie die Integration von ESG die Unternehmensleistung st\u00e4rkt. F\u00fcr Family Offices bieten solche Rahmenwerke intellektuelle Unterst\u00fctzung f\u00fcr Praktiken, die bereits mit ihren Reputations- und Legacy-Zielen \u00fcbereinstimmen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa7bd83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa7bd83\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95c1b47\" data-id=\"95c1b47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c97fad4 elementor-widget elementor-widget-heading\" data-id=\"c97fad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ausgewogene Mittelzuweisungen, keine blinden Verpflichtungen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b121abd elementor-widget elementor-widget-text-editor\" data-id=\"b121abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Es w\u00e4re falsch zu behaupten, dass Family Offices ihr gesamtes Verm\u00f6gen in gr\u00fcne Technologien stecken.<\/b><span style=\"font-weight: 400;\"> Die Daten von UBS zeigen, dass die Portfolios im Jahr 2024 neu gewichtet wurden. Der Anteil an festverzinslichen Wertpapieren aus den Industriel\u00e4ndern erreichte den h\u00f6chsten Wert seit f\u00fcnf Jahren, da Familien in Zeiten volatiler M\u00e4rkte nach Stabilit\u00e4t suchten. Auch die regionalen Allokationen bleiben diversifiziert: 50 Prozent in Nordamerika, 27 Prozent in Westeuropa und 17 Prozent im asiatisch-pazifischen Raum. ESG f\u00fcgt sich in dieses breitere Bild ein. Es handelt sich nicht um einen Massentransfer, sondern um eine gemischte Komponente von diversifizierten Investitionen.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10314d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10314d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0bd07d\" data-id=\"f0bd07d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d03919 elementor-widget elementor-widget-heading\" data-id=\"2d03919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Das Ausma\u00df der nachhaltigen Finanzierung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1c6c25 elementor-widget elementor-widget-text-editor\" data-id=\"f1c6c25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Die Dynamik der globalen nachhaltigen Finanzwirtschaft ist langfristig angelegt.<\/b><span style=\"font-weight: 400;\"> Chinas Markt f\u00fcr gr\u00fcne Anleihen erreichte Ende 2022 ein Volumen von $489 Milliarden US-Dollar und ist damit der gr\u00f6\u00dfte nationale Markt nach Europa (Wikipedia, 2025). Die Internationale Agentur f\u00fcr erneuerbare Energien (2023) berichtet, dass im Jahr 2023 $200 Milliarden US-Dollar in die Infrastruktur f\u00fcr erneuerbare Energien investiert wurden, was einer Steigerung von 75 <\/span><span style=\"font-weight: 400;\">Prozent mehr als im Jahr zuvor. In saubere Technologien flossen $1,9 Billionen US von den $3 Billionen US, die im Laufe des Jahres weltweit in Energie investiert wurden. Dies sind keine marginalen Str\u00f6me. Sie zeigen, dass die nachhaltige Finanzierung heute Teil der globalen Finanzarchitektur ist, auch wenn die politischen Narrative schwanken. Die Schweiz ist ein Beispiel f\u00fcr eine solche globale Dynamik. Z\u00fcrich und Genf geh\u00f6ren zu den f\u00fchrenden Zentren f\u00fcr nachhaltige Verm\u00f6gensverwaltung und das Land hat sich verpflichtet, bis 2050 eine Netto-Null-Strategie zu verfolgen. Schweizer Family Offices haben den Ton angegeben, wenn es darum geht, ESG-Rahmenwerke zu begr\u00fc\u00dfen und von den strengeren Offenlegungsanforderungen in Europa und der Harmonisierung mit globalen Taxonomien zu profitieren. Weltweit entf\u00e4llt die \u00fcberwiegende Mehrheit der ESG-Verm\u00f6genswerte auf Europa, w\u00e4hrend Asien, insbesondere Singapur und Hongkong, schnell w\u00e4chst. Family Officers auf der ganzen Welt navigieren daher nicht nur durch die finanziellen M\u00f6glichkeiten, sondern auch durch ein regulatorisches Umfeld, das zunehmend eine glaubw\u00fcrdige Nachhaltigkeitsberichterstattung erfordert.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44ec45c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44ec45c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f1e9c3\" data-id=\"0f1e9c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17e26ab elementor-widget elementor-widget-heading\" data-id=\"17e26ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Die Governance-Herausforderung f\u00fcr Family Offices<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f745c8 elementor-widget elementor-widget-text-editor\" data-id=\"5f745c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Die \u00dcberzeugung ist gro\u00df, doch die Umsetzung ist komplex. ESG-Verm\u00f6genswerte erstrecken sich \u00fcber verschiedene Anlageklassen und Rechtsordnungen. Die Messung sowohl der finanziellen Ertr\u00e4ge als auch der \u00f6kologischen und sozialen Auswirkungen erfordert konsolidierte Daten und eine einheitliche Berichterstattung. <\/span><b>Hier kommen die digitalen Plattformen ins Spiel. <\/b><span style=\"font-weight: 400;\">Sie fassen die Daten mehrerer Banken und Verm\u00f6genswerte in einer einzigen sicheren Schnittstelle zusammen und erm\u00f6glichen es Family Offices, Engagements zu \u00fcberwachen, alle relevanten Verpflichtungen zu verfolgen und transparent zu berichten. F\u00fcr verm\u00f6gende Familien ist Klarheit nicht nur eine praktische Erleichterung, sondern auch die Grundlage f\u00fcr die Unternehmensf\u00fchrung. Die F\u00e4higkeit der Plattform, Transparenz, Governance und Reporting zu kombinieren, ist eine direkte Antwort auf die Herausforderungen, denen sich Family Offices bei der Einbindung von ESG in langfristige Verm\u00f6gensstrategien gegen\u00fcbersehen.<\/span><span style=\"font-weight: 400;\"><br><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98cd89e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98cd89e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc06b03\" data-id=\"cc06b03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bc7611 elementor-widget elementor-widget-image\" data-id=\"1bc7611\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"418\" src=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/12\/analysis-1024x535.png\" class=\"attachment-large size-large wp-image-29032\" alt=\"Altoo-Wealth-Plattform\" srcset=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/12\/analysis-1024x535.png 1024w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/12\/analysis-300x157.png 300w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/12\/analysis-768x401.png 768w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/12\/analysis-18x9.png 18w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/12\/analysis-600x314.png 600w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/12\/analysis.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b83193 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b83193\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fbda77\" data-id=\"7fbda77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8b4315 elementor-widget elementor-widget-heading\" data-id=\"b8b4315\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Erbe, nicht Mode<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c140f80 elementor-widget elementor-widget-text-editor\" data-id=\"c140f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>F\u00fcr Family Offices ist ESG kein Trend, den man aufgibt, wenn sich die Politik \u00e4ndert.<\/b><span style=\"font-weight: 400;\"> Es ist ein Rahmen f\u00fcr das Risikomanagement, eine Komponente der treuh\u00e4nderischen Pflicht und eine M\u00f6glichkeit, Verm\u00f6gen und Werte \u00fcber die Generationen hinweg in Einklang zu bringen. Politische Zyklen k\u00f6nnen die Stimmung st\u00f6ren, aber sie k\u00f6nnen die strukturellen Triebkr\u00e4fte der sauberen Technologie\u00f6konomie, die Leistungsdaten der Anleger oder die treuh\u00e4nderischen Erwartungen nicht aushebeln.<\/span><\/p><p><span style=\"font-weight: 400;\">In diesem Sinne geht es bei ESG nicht nur um kurzfristige Risiken und Ertr\u00e4ge. Es geht auch um das Erbe. Die Architektur von Family Offices (lange Zeithorizonte, Governance-Rahmen und Kapitalflexibilit\u00e4t) macht sie zu nat\u00fcrlichen Vorreitern bei der Einbindung von Nachhaltigkeit in die Verm\u00f6gensverwaltung.<\/span><\/p><p><span style=\"font-weight: 400;\"><b>F\u00fcr Familienbeauftragte ist es wichtig, Verschiebungen zu antizipieren. <\/b>Politische Zyklen k\u00f6nnen Fondsstr\u00f6me erschweren, aber Family Offices mit einem langfristigen Horizont k\u00f6nnen es sich nicht leisten, ESG zu ignorieren. Die Aufgabe besteht nicht nur darin, zu investieren, sondern auch klar zu messen, zu steuern und zu berichten - und damit sicherzustellen, dass Nachhaltigkeitsstrategien nicht nur rhetorisch bleiben, sondern in die Praxis umgesetzt werden. Plattformen wie Altoo geben den Verantwortlichen die Instrumente an die Hand, um diese Klarheit zu schaffen und das Erbe der Familie zu sichern.<br \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba6a97e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba6a97e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18db505\" data-id=\"18db505\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8df4125 elementor-widget elementor-widget-heading\" data-id=\"8df4125\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Von der Frage zum Handeln: Der Spickzettel des Familienbeauftragten<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a834452 family-office-table elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a834452\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d473517\" data-id=\"d473517\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce5f856 elementor-widget elementor-widget-html\" data-id=\"ce5f856\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"table-container\">\r\n    <!-- Desktop Table -->\r\n    <table>\r\n      <thead>\r\n        <tr>\r\n          <th>Was haben Sie auf dem Herzen?<\/th>\r\n          <th>Warum das wichtig ist<\/th>\r\n          <th>Praktischer Umzug<\/th>\r\n        <\/tr>\r\n      <\/thead>\r\n      <tbody>\r\n        <tr>\r\n          <td>\"Haben die ESG Auswirkungen auf meine t\u00e4gliche Arbeit?\"<\/td>\r\n          <td>Die ESG-Berichterstattung betrifft alle Banken, Verwahrstellen und Anlageklassen. Ohne Aufsicht vervielfachen sich die blinden Flecken.<\/td>\r\n          <td>Nutzen Sie Tools, die Daten konsolidieren, so dass Sie ESG nahtlos \u00fcberwachen und Auftraggeber vertrauensvoll informieren k\u00f6nnen.<\/td>\r\n        <\/tr>\r\n        <tr>\r\n          <td>\"Wie bewerte ich ESG, wenn Bilder das Bild tr\u00fcben?\"<\/td>\r\n          <td>Performance-Daten: Nachhaltige Fonds haben f\u00fcnf Jahre lang und sogar noch Anfang 2025 besser abgeschnitten als vergleichbare Fonds.<\/td>\r\n          <td>Nutzen Sie Fakten, nicht Gef\u00fchle. Vergleichen Sie Ihre Portfolios mit Indizes, um Entscheidungen zu treffen.<\/td>\r\n        <\/tr>\r\n        <tr>\r\n          <td>\"Was ist wichtiger: die Politik oder das Erbe?\"<\/td>\r\n          <td>In Europa befinden sich 85% ESG-Verm\u00f6genswerte, die Schweiz ist eine Drehscheibe f\u00fcr nachhaltiges Verm\u00f6gen, und Asien w\u00e4chst schnell.<\/td>\r\n          <td>Betrachten Sie ESG als Teil der langfristigen Legacy-Planung. Politische Zyklen sind das Rauschen; der Generationenhorizont ist das Signal.<\/td>\r\n        <\/tr>\r\n      <\/tbody>\r\n    <\/table>\r\n\r\n    <!-- Mobile Cards -->\r\n    <div class=\"card\">\r\n      <div class=\"card-section first-column\">\r\n        <div class=\"label\">Was haben Sie auf dem Herzen?<\/div>\r\n        <div class=\"value\">\"Haben die ESG Auswirkungen auf meine t\u00e4gliche Arbeit?\"<\/div>\r\n      <\/div>\r\n      <div class=\"card-section other-column\">\r\n        <div class=\"label\">Warum das wichtig ist<\/div>\r\n        <div class=\"value\">Die ESG-Berichterstattung betrifft alle Banken, Verwahrstellen und Anlageklassen. Ohne Aufsicht vervielfachen sich die blinden Flecken.<\/div>\r\n      <\/div>\r\n      <div class=\"card-section other-column\">\r\n        <div class=\"label\">Praktischer Umzug<\/div>\r\n        <div class=\"value\">Nutzen Sie Tools, die Daten konsolidieren, so dass Sie ESG nahtlos \u00fcberwachen und Auftraggeber vertrauensvoll informieren k\u00f6nnen.<\/div>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"card\">\r\n      <div class=\"card-section first-column\">\r\n        <div class=\"label\">Was haben Sie auf dem Herzen?<\/div>\r\n        <div class=\"value\">\"Wie bewerte ich ESG, wenn Bilder das Bild tr\u00fcben?\"<\/div>\r\n      <\/div>\r\n      <div class=\"card-section other-column\">\r\n        <div class=\"label\">Warum das wichtig ist<\/div>\r\n        <div class=\"value\">Performance-Daten: Nachhaltige Fonds haben f\u00fcnf Jahre lang und sogar noch Anfang 2025 besser abgeschnitten als vergleichbare Fonds.<\/div>\r\n      <\/div>\r\n      <div class=\"card-section other-column\">\r\n        <div class=\"label\">Praktischer Umzug<\/div>\r\n        <div class=\"value\">Nutzen Sie Fakten, nicht Gef\u00fchle. Vergleichen Sie Ihre Portfolios mit Indizes, um Entscheidungen zu treffen.<\/div>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"card\">\r\n      <div class=\"card-section first-column\">\r\n        <div class=\"label\">Was haben Sie auf dem Herzen?<\/div>\r\n        <div class=\"value\">\"Was ist wichtiger: die Politik oder das Erbe?\"<\/div>\r\n      <\/div>\r\n      <div class=\"card-section other-column\">\r\n        <div class=\"label\">Warum das wichtig ist<\/div>\r\n        <div class=\"value\">In Europa befinden sich 85% ESG-Verm\u00f6genswerte, die Schweiz ist eine Drehscheibe f\u00fcr nachhaltiges Verm\u00f6gen, und Asien w\u00e4chst schnell.<\/div>\r\n      <\/div>\r\n      <div class=\"card-section other-column\">\r\n        <div class=\"label\">Praktischer Umzug<\/div>\r\n        <div class=\"value\">Betrachten Sie ESG als Teil der langfristigen Legacy-Planung. Politische Zyklen sind das Rauschen; der Generationenhorizont ist das Signal.<\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ac2ef3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ac2ef3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9429528\" data-id=\"9429528\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a45f293 elementor-widget elementor-widget-text-editor\" data-id=\"a45f293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><span style=\"font-weight: 400;\">Wir von Altoo AG sind ein <\/span><\/i><b><i>Anbieter digitaler Verm\u00f6gensverwaltung f\u00fcr Family Offices<\/i><\/b><i><span style=\"font-weight: 400;\">. Wir bieten zwar keine Anlageberatung an, aber wir helfen Ihnen, \u00fcber die Trends informiert zu bleiben, die Ihre Gesch\u00e4fte beeinflussen: von der ESG-Integration bis zu den sich entwickelnden Anforderungen an die Unternehmensf\u00fchrung.<\/span><\/i><\/p><p><i><span style=\"font-weight: 400;\">F\u00fcr tiefere Einblicke in die Art und Weise, wie Family Offices zielstrebig und pr\u00e4zise in die Zukunft navigieren, <\/span><\/i><a href=\"https:\/\/altoo.io\/de\/elite-wealth-ebook-die-kunst-eines-erfolgreichen-family-offices\/\"><b><i>Laden Sie unser kostenloses eBook herunter: Die Kunst eines erfolgreichen Family Office<\/i><\/b><i><span style=\"font-weight: 400;\">.<\/span><\/i><i><span style=\"font-weight: 400;\"><br \/><\/span><\/i><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Das politische Klima f\u00fcr nachhaltige Finanzen hat sich in den Vereinigten Staaten abgek\u00fchlt. Die R\u00fcckkehr von Donald Trump ins Wei\u00dfe Haus hat die Unterst\u00fctzung f\u00fcr Umwelt-, Sozial- und Governance-Politik (ESG) geschw\u00e4cht. Die Mittelzufl\u00fcsse zeigen, dass der Enthusiasmus bei einigen institutionellen Anlegern nachgelassen hat. Aus der Sicht von Family Offices sieht das Bild jedoch ganz anders aus. Diese privaten Vehikel, die das Verm\u00f6gen von sehr wohlhabenden Familien verwalten, halten weiterhin an nachhaltigen Investitionen fest.<\/p>","protected":false},"author":12,"featured_media":41435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,1057,86,233,57,89,87,68],"tags":[1157,1032],"class_list":["post-41288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-beyond-wealth","category-explore-by-entity","category-family-office","category-lifestyle","category-multi-family-office","category-single-family-office","category-well-being","tag-esg-investing","tag-template-3"],"_links":{"self":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/41288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/comments?post=41288"}],"version-history":[{"count":32,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/41288\/revisions"}],"predecessor-version":[{"id":41327,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/41288\/revisions\/41327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media\/41435"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media?parent=41288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories?post=41288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/tags?post=41288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}