{"id":27305,"date":"2023-11-17T10:00:36","date_gmt":"2023-11-17T09:00:36","guid":{"rendered":"https:\/\/altoo.io\/?p=27305"},"modified":"2023-11-17T09:29:10","modified_gmt":"2023-11-17T08:29:10","slug":"die-lauder-stiftung-ein-philanthropisches-kraftpaket","status":"publish","type":"post","link":"https:\/\/altoo.io\/de\/the-lauder-foundation-a-philanthropic-powerhouse\/","title":{"rendered":"Die Lauder Stiftung: Ein philanthropisches Kraftpaket"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"27305\" class=\"elementor elementor-27305\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bba4391 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bba4391\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da9945f\" data-id=\"da9945f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cde3d07 elementor-widget elementor-widget-text-editor\" data-id=\"cde3d07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Hintergrund und Mission<\/b><\/h4><p><span style=\"font-weight: 400;\">Leonard und Evelyn Lauder, die Erben des Kosmetikverm\u00f6gens von Est\u00e9e Lauder, haben ihr Leben der Philanthropie gewidmet und wollen die Welt ver\u00e4ndern. Die Stiftung wurde ins Leben gerufen, um ihre Ressourcen und ihren Einfluss f\u00fcr Zwecke zu nutzen, die ihnen am Herzen liegen. Auch wenn die Stiftung ein niedriges Profil hat, so ist ihr Einfluss doch weitreichend. Der Schwerpunkt liegt auf der Unterst\u00fctzung von Organisationen, die sich f\u00fcr Demokratie, globale Entwicklung, Bildung, Kunst und Kultur, j\u00fcdische Belange und die Erforschung von Krankheiten einsetzen.<\/span><\/p><p>\u00a0<\/p><h4><b>Schwerpunktgebiete<\/b><\/h4><p><span style=\"font-weight: 400;\">Einer der wichtigsten F\u00f6rderer der Lauder Foundation ist das Aspen Institute, eine Organisation, die sich der F\u00f6rderung von F\u00fchrungskr\u00e4ften und der Bew\u00e4ltigung globaler Herausforderungen widmet. Als Treuh\u00e4nder und Vorsitzender des Internationalen Ausschusses des Instituts hat Leonard Lauder eine entscheidende Rolle bei der Gestaltung der Programme und Initiativen des Instituts gespielt. Die Stiftung hat das Aspen Institute in den letzten Jahren mit insgesamt rund 780.000 Dollar finanziell unterst\u00fctzt.<\/span><\/p><p><span style=\"font-weight: 400;\">Die Lauder Foundation legt gro\u00dfen Wert auf qualitativ hochwertige Bildung und unterst\u00fctzt Schulen der Klassen K-12, insbesondere private College-Vorbereitungseinrichtungen wie die Pilgrim School in Los Angeles, die Lake Highland Preparatory School und die First Academy in Orlando, Florida. Sie unterst\u00fctzt auch Bildungsprogramme in \u00f6ffentlichen Bibliotheken, wie der Greenwich Library in Connecticut und der Winter Park Public Library in Florida. Im Bereich der Hochschulbildung hat die Stiftung das Hunter College und das Army War College unterst\u00fctzt. Ihre Steuererkl\u00e4rungen zeigen ein starkes Engagement f\u00fcr eine umfassende Bildung von der Vorschule bis zur 12.<\/span><\/p><p><span style=\"font-weight: 400;\">Obwohl die Lauder Foundation ihre Priorit\u00e4ten bei der Vergabe von F\u00f6rdermitteln f\u00fcr Kunst und Kultur nicht explizit angibt, lassen ihre Steuererkl\u00e4rungen auf ein starkes Interesse an der Unterst\u00fctzung einer Vielzahl von kulturellen Organisationen schlie\u00dfen. Zu den Zuschussempf\u00e4ngern der letzten Zeit geh\u00f6ren so renommierte Einrichtungen wie die Frick Collection, die Metropolitan Opera, der New Yorker Botanische Garten und die Statue of Liberty\/Ellis Island Foundation. Das Engagement der Stiftung f\u00fcr Kunst und Kultur geht \u00fcber New York City hinaus und umfasst auch die Unterst\u00fctzung des Glimmerglass Opera Theatre in Cooperstown, New York.<\/span><\/p><p><span style=\"font-weight: 400;\">Die Lauder Foundation engagiert sich seit langem f\u00fcr die Unterst\u00fctzung j\u00fcdischer Anliegen. Obwohl dieser Bereich nur einen kleinen Teil ihrer gesamten Zuwendungen ausmacht, hat die Stiftung eine Vielzahl von j\u00fcdischen Organisationen in den gesamten Vereinigten Staaten unterst\u00fctzt. Zu den Empf\u00e4ngern geh\u00f6ren das National Museum of American Jewish History, der Jewish Communal Fund, die Gideon Hausner Jewish Day School in Kalifornien, das American Jewish Committee und National Jewish Health, ein Forschungskrankenhaus mit Sitz in Denver, Colorado.<\/span><\/p><p><span style=\"font-weight: 400;\">Obwohl die Lauder Foundation sich nicht in erster Linie auf die Erforschung von Krankheiten konzentriert, hat sie in diesem Bereich bemerkenswerte Beitr\u00e4ge geleistet. Die Stiftung hat ausgew\u00e4hlten Organisationen, die sich der Erforschung, Pr\u00e4vention und Behandlung von Krankheiten widmen, Zusch\u00fcsse gew\u00e4hrt. Insbesondere hat sie die Elton John AIDS Foundation und die Alzheimer's Drug Discovery Foundation unterst\u00fctzt, bei der Leonard Lauder als Co-Vorsitzender fungiert. Die Familie Lauder hat bis 2033 200 Millionen Dollar zugesagt, um die Forschung zur Behandlung und Pr\u00e4vention der Alzheimer-Krankheit zu beschleunigen.<\/span><\/p><p>\u00a0<\/p><h4><b>Auswirkungen<\/b><\/h4><p><span style=\"font-weight: 400;\">In den letzten Jahren hat die Lauder Foundation j\u00e4hrlich zwischen 3 und 4 Millionen Dollar an Zusch\u00fcssen vergeben. Die Zuwendungen der Stiftung reichen von 2.000 bis 1 Million Dollar, wobei gr\u00f6\u00dfere Betr\u00e4ge in der Regel an Organisationen gehen, an denen Leonard Lauder pers\u00f6nlich beteiligt ist. Der Einfluss der Stiftung zeigt sich in den vielen Organisationen und Projekten, die sie innerhalb und au\u00dferhalb von New York City unterst\u00fctzt hat. Das Engagement der Stiftung f\u00fcr eine kontinuierliche Unterst\u00fctzung und das pers\u00f6nliche Engagement ihres Gr\u00fcnders haben es ihr erm\u00f6glicht, das Leben von Menschen und Gemeinschaften entscheidend zu ver\u00e4ndern.<\/span><\/p><p><span style=\"font-weight: 400;\">Die von Leonard und Evelyn Lauder gef\u00fchrte Lauder Foundation hat sich zu einem philanthropischen Kraftzentrum in New York City entwickelt. Die Stiftung, die sich auf die Unterst\u00fctzung von Projekten konzentriert, die mit den pers\u00f6nlichen Interessen der Gr\u00fcnder \u00fcbereinstimmen, hat bedeutende Beitr\u00e4ge in den Bereichen Bildung, Kunst und Kultur, j\u00fcdische Projekte und Krankheitsforschung geleistet. Auch wenn die Stiftung f\u00fcr neue Organisationen nicht leicht zug\u00e4nglich ist, ist ihr Einfluss unbestreitbar. Die kontinuierliche Unterst\u00fctzung und das Engagement der Lauder Foundation f\u00fcr einen positiven Wandel haben ein bleibendes Verm\u00e4chtnis in der Gemeinschaft hinterlassen und sie zu einem Leuchtturm der Hoffnung und des Fortschritts f\u00fcr Bed\u00fcrftige gemacht.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Lauder Foundation ist eine bekannte philanthropische Organisation mit Sitz in New York City. Sie wurde 1987 von Leonard A. Lauder, dem Sohn des Kosmetikunternehmers Est\u00e9e Lauder, und seiner Frau Evelyn gegr\u00fcndet. Die Stiftung hat bedeutende Beitr\u00e4ge in einer Vielzahl von Bereichen geleistet, darunter Bildung, Kunst und Kultur, j\u00fcdische Anliegen und Krankheitsforschung. Mit ihrem Schwerpunkt auf der Unterst\u00fctzung von Organisationen, die mit den pers\u00f6nlichen Interessen ihrer Gr\u00fcnder \u00fcbereinstimmen, hat die Lauder Foundation eine entscheidende Rolle bei der F\u00f6rderung positiver Ver\u00e4nderungen in der Gemeinschaft gespielt.<\/p>","protected":false},"author":12,"featured_media":27387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,73,57,545,82,67],"tags":[834],"class_list":["post-27305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-explore-by-topic","category-lifestyle","category-people","category-philantrophy","category-philantropy","tag-lauder-foundation"],"_links":{"self":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/27305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/comments?post=27305"}],"version-history":[{"count":8,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/27305\/revisions"}],"predecessor-version":[{"id":27384,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/27305\/revisions\/27384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media\/27387"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media?parent=27305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories?post=27305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/tags?post=27305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}