{"id":17137,"date":"2023-08-08T10:00:55","date_gmt":"2023-08-08T08:00:55","guid":{"rendered":"https:\/\/altoo.io\/?p=17137"},"modified":"2023-08-07T14:38:47","modified_gmt":"2023-08-07T12:38:47","slug":"jorge-paulo-lemann-der-reichste-mann-brasiliens","status":"publish","type":"post","link":"https:\/\/altoo.io\/de\/jorge-paulo-lemann-brazils-wealthiest-man\/","title":{"rendered":"Die Drei Musketiere: Eine starke Partnerschaft"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"17137\" class=\"elementor elementor-17137\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-087cb74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"087cb74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dc858d\" data-id=\"7dc858d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a0ecab elementor-widget elementor-widget-text-editor\" data-id=\"1a0ecab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Aufbau einer revolution\u00e4ren Unternehmenskultur<\/strong><\/h4><p><span style=\"font-weight: 400;\">Nach einer kurzen Tenniskarriere gr\u00fcndete Lemann 1971 die Banco Garantia mit dem Ziel, sie zum brasilianischen Goldman Sachs-\u00c4quivalent zu machen. Mit Partnern Marcel Herrmann Telles und Carlos Alberto Sicupira ver\u00e4nderten sie die Gesch\u00e4ftswelt, indem sie eine meritokratische Kultur einf\u00fchrten, die Hierarchie und Elitismus abbaute, und unter Lemanns F\u00fchrung wurde Garantia zu einer legend\u00e4ren Investmentfirma in Brasilien, bekannt f\u00fcr die Erh\u00f6hung der Gewinnmargen und Effizienz.<\/span><\/p><p><span style=\"font-weight: 400;\">Zu den innovativen Praktiken geh\u00f6rten Open-Plan-B\u00fcros, das Verbot von Sammelobjekten und die Belohnung von Top-Performern mit Aktien anstelle von traditionellen Boni. Diese \"unternehmerische Revolution\" konzentrierte sich auf Talent und Meritokratie und hatte einen dauerhaften Einfluss auf die brasilianische Gesch\u00e4ftslandschaft.<\/span><b>\u00a0<\/b><\/p><h4><b>Die Drei Musketiere<\/b><\/h4><p><span style=\"font-weight: 400;\">Lemanns langj\u00e4hrige Gesch\u00e4ftspartner Marcel Herrmann-Telles und Carlos Alberto Sicupira sind ein integraler Bestandteil seines Erfolgs. Das formidable Trio, in Brasilien als die \"Drei Musketiere\" bekannt, ver\u00e4nderte die Gesch\u00e4ftskultur des Landes. Telles mit einem Nettoverm\u00f6gen von 13 Milliarden US-Dollar und Sicupira mit einem Nettowert von 11,3 Milliarden Dollar kletterten in die Reihen der brasilianischen Reichenliste. Gemeinsam setzten sie ihre innovativen Gesch\u00e4ftsstrategien in verschiedenen Branchen erfolgreich um.<\/span><b>\u00a0<\/b><\/p><h4><b>Diversifizierung von Investitionen und hochkar\u00e4tige Akquisitionen<\/b><\/h4><p><span style=\"font-weight: 400;\">Lemanns Investmentfirma 3G Capital machte sich mit hochkar\u00e4tigen Akquisitionen, darunter bekannte Marken wie Budweiser und Burger King, einen Namen. Joint Ventures mit Warren Buffett, wie das Eigentum an Heinz, f\u00fcgten zu ihrem bemerkenswerten Portfolio hinzu. Lemanns vision\u00e4re Herangehensweise an das Gesch\u00e4ft verbreitete sich und verwandelte k\u00e4mpfende Unternehmen in florierende Unternehmen.<\/span><b>\u00a0<\/b><\/p><h4><b>Investitionsstrategie\u00a0<\/b><\/h4><p><span style=\"font-weight: 400;\">Was 3G Capital unterscheidet, ist seine einzigartige Methode zur Finanzierung gro\u00dfer Anschaffungen. Lemann unterh\u00e4lt einen engen Kreis von superreichen Familien als Investoren, darunter die Familie Santo Domingo aus Kolumbien und die Familie Reimann aus Deutschland, um die Vertraulichkeit f\u00fcr bevorstehende Gesch\u00e4fte zu gew\u00e4hrleisten. Bemerkenswert ist, dass sich Finanzeliten wie Roger Federer und William Ackman seinem internationalen Traumteam angeschlossen haben, da Lemann seinen Ruf f\u00fcr die Schaffung von Wohlstand hat.<\/span><\/p><p><span style=\"font-weight: 400;\">Mit einem Buy-and-Hold-Ansatz und der F\u00e4higkeit, Gewinne zu steigern, sprechen die erfolgreichen \u00dcbernahmen von 3G Capital f\u00fcr sich. Lemann belebt k\u00e4mpfende Unternehmen durch Kostensenkungen, Management-Restrukturierung und Produktivit\u00e4tsfokus, um langfristigen Erfolg zu gew\u00e4hrleisten.<\/span><b>\u00a0<\/b><\/p><h4><b>Sportliche Verfolgung und Lebensunterricht<\/b><\/h4><p><span style=\"font-weight: 400;\">Lemanns gesch\u00e4ftliche Leistungen sind bekannt, aber auch seine Leidenschaft f\u00fcr den Sport hat sein Leben gepr\u00e4gt. Als ehemaliger professioneller Tennisspieler vertrat er Brasilien und die Schweiz im Davis Cup und wurde f\u00fcnfmal Nationalmeister. Nach Wimbledon wandte er seine Aufmerksamkeit auf die Finanzen, um dort erfolgreich zu sein.<\/span><\/p><p><span style=\"font-weight: 400;\">Seine Liebe zum Sport und die Lektionen, die er auf dem Tennisplatz lernte, beeinflussten seinen Ansatz f\u00fcr das Gesch\u00e4ft. Genauso wie er Herausforderungen im Sport umarmt, nimmt Lemann berechnete Risiken und Chancen ein. Es verdient ihm einen Ruf als k\u00fchner und vision\u00e4rer Leader im Gesch\u00e4ft.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Jorge Paulo Lemann, ein Selfmade-Milliard\u00e4r und einer der erfolgreichsten Wirtschaftsf\u00fchrer der Welt, hat die Gesch\u00e4ftskultur in Brasilien revolutioniert. Mit einem Nettoverm\u00f6gen von $15,2 Milliarden reicht Lemanns Einfluss \u00fcber die Finanzwelt hinaus. Wie haben Lemanns Aufstieg und seine Gesch\u00e4ftsstrategien die brasilianische Unternehmenslandschaft ver\u00e4ndert?<\/p>","protected":false},"author":12,"featured_media":17138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,69,57,88],"tags":[420,419],"class_list":["post-17137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-art-and-culture","category-lifestyle","category-private-wealth-owners","tag-brazils-wealthiest-man","tag-jorge-paulo-lemann"],"_links":{"self":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/17137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/comments?post=17137"}],"version-history":[{"count":7,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/17137\/revisions"}],"predecessor-version":[{"id":17224,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/17137\/revisions\/17224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media\/17138"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media?parent=17137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories?post=17137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/tags?post=17137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}