{"id":13475,"date":"2023-07-04T10:00:39","date_gmt":"2023-07-04T08:00:39","guid":{"rendered":"https:\/\/altoo.io\/?p=13475"},"modified":"2023-07-03T15:10:31","modified_gmt":"2023-07-03T13:10:31","slug":"wie-fuhle-ich-mich-besser","status":"publish","type":"post","link":"https:\/\/altoo.io\/de\/how-to-feel-better\/","title":{"rendered":"Wie man sich gleich besser f\u00fchlt!"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"13475\" class=\"elementor elementor-13475\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b431a91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b431a91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d393718\" data-id=\"d393718\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a251f9d elementor-widget elementor-widget-text-editor\" data-id=\"a251f9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Bewegung und Entspannung<\/b><b><br \/><\/b><\/h4><p><span style=\"font-weight: 400\">Haben Sie schon von Qigong geh\u00f6rt? Diese Geist-K\u00f6rper-\u00dcbung ist<\/span> <span style=\"font-weight: 400\">ein wesentlicher Aspekt der traditionellen chinesischen Medizin. Sie verbindet Elemente der Kampfk\u00fcnste, wird aber mit langsamen und flie\u00dfenden Bewegungen ausgef\u00fchrt. Daher betrachten viele Qigong als eine Art meditativer Bewegung. <\/span><span style=\"font-weight: 400\">Atem-, K\u00f6rper- und Bewegungs\u00fcbungen, Konzentrations- und Meditations\u00fcbungen sind Teil dieser Praxis.<\/span><\/p><p><span style=\"font-weight: 400\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-13479 size-full aligncenter\" src=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/07\/Text-Quigong.jpg\" alt=\"\" width=\"768\" height=\"261\" srcset=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/07\/Text-Quigong.jpg 768w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/07\/Text-Quigong-300x102.jpg 300w, https:\/\/altoo.io\/live01\/wp-content\/uploads\/2023\/07\/Text-Quigong-18x6.jpg 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/> <\/span><span style=\"font-weight: 400\"><br \/><\/span><span style=\"font-weight: 400\"><br \/><\/span><b>Meditieren<\/b><\/p><p><span style=\"font-weight: 400\">Meditations\u00fcbungen k\u00f6nnen helfen, sich auf den Augenblick zu konzentrieren, negative Gedankenspiralen loszulassen und Klarheit im Denken zu finden. Dar\u00fcber hinaus f\u00f6rdern Meditationstechniken und -\u00fcbungen die Achtsamkeit, was es leichter macht, sich der eigenen k\u00f6rperlichen und emotionalen Situation bewusst zu werden und aufgestauten Stress abzubauen.<\/span><\/p><p><b>Gesunde Ern\u00e4hrung und guter Trinkregime<\/b><\/p><p><span style=\"font-weight: 400\">Dieser Tipp ist so einfach, aber nur wenige befolgen ihn. Bewegung, Schlaf und eine ausgewogene Ern\u00e4hrung k\u00f6nnte man als die Eckpfeiler des Wohlbefindens bezeichnen. Die Ern\u00e4hrung versorgt Ihr System mit den besten N\u00e4hrstoffen, und die empfohlene Menge an Wasser sorgt daf\u00fcr, dass die N\u00e4hrstoffe die Organe bestm\u00f6glich erreichen. Je mehr Vitalstoffe und je weniger Schadstoffe in Ihrer Ern\u00e4hrung enthalten sind, desto weniger Energie muss Ihr K\u00f6rper aufwenden, um alle seine Funktionen bestm\u00f6glich zu erf\u00fcllen.<\/span><\/p><h4><b>Frische Luft und Sonnenlicht<\/b><\/h4><p><span style=\"font-weight: 400\">Wenn man sich im Alltag nicht wohlf\u00fchlt und weder der Kopf noch der K\u00f6rper in guter Verfassung sind, kann ein Spaziergang an der frischen Luft eine L\u00f6sung sein. Die K\u00f6rperzellen werden durch den vermehrten Zufluss von Sauerstoff gest\u00e4rkt, in Kombination mit leichter Bewegung tr\u00e4gt dies zur Verbesserung der Gesundheit bei. Schon 20-30 Minuten t\u00e4gliche Bewegung an der frischen Luft k\u00f6nnen das Wohlbefinden nachhaltig verbessern.<\/span><\/p><p><span style=\"font-weight: 400\">Um das allgemeine Wohlbefinden zu steigern, sind einige Faktoren notwendig, die jedoch schrittweise umgesetzt werden k\u00f6nnen und in der Regel keine radikale \u00c4nderung des t\u00e4glichen Lebens erfordern. Auch wenn sie auf den ersten Blick sanft erscheinen, haben sie langfristig eine positive Wirkung auf K\u00f6rper und Geist.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ganz gleich, ob Sie morgens nur schwer in die G\u00e4nge kommen, nachmittags zu einer Flaute neigen oder sich am Ende des Tages v\u00f6llig ausgelaugt f\u00fchlen - Experten zufolge k\u00f6nnen schon kleine Ver\u00e4nderungen in Ihrem Lebensstil einen gro\u00dfen Einfluss auf Ihre Energie haben. Hier erfahren Sie, wie Sie wieder in die Spur kommen.<\/p>","protected":false},"author":12,"featured_media":13477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[184,57,68],"tags":[],"class_list":["post-13475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-all-insights","category-lifestyle","category-well-being"],"_links":{"self":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/13475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/comments?post=13475"}],"version-history":[{"count":10,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/13475\/revisions"}],"predecessor-version":[{"id":13533,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/13475\/revisions\/13533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media\/13477"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media?parent=13475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories?post=13475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/tags?post=13475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}