{"id":10404,"date":"2023-06-14T06:17:39","date_gmt":"2023-06-14T06:17:39","guid":{"rendered":"https:\/\/staging.altoo.io\/?p=10404"},"modified":"2023-11-21T07:29:03","modified_gmt":"2023-11-21T06:29:03","slug":"was-man-uber-bill-gates-wissen-sollte-der-den-globalen-wandel-mitgestaltet","status":"publish","type":"post","link":"https:\/\/altoo.io\/de\/what-to-know-about-bill-gates-shaping-the-global-change\/","title":{"rendered":"Was man \u00fcber Bill Gates und die Gestaltung des globalen Wandels wissen sollte"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10404\" class=\"elementor elementor-10404\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba3e814 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba3e814\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ff77f1c\" data-id=\"ff77f1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c91b5cf elementor-widget elementor-widget-image\" data-id=\"c91b5cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altoo.io\/live01\/wp-content\/uploads\/elementor\/thumbs\/AdobeStock_443054297-scaled-qett5t6qig4fv62xnszm8hjxs1vhp0jykgwoyg7yxk.jpeg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-b9ddb62\" data-id=\"b9ddb62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6da7fbf elementor-widget elementor-widget-text-editor\" data-id=\"6da7fbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>\u00a0<\/h3><h3>Die Gestaltung des digitalen Zeitalters und dar\u00fcber hinaus<\/h3><p>Gates machte sich zun\u00e4chst als Mitbegr\u00fcnder von Microsoft einen Namen, ein Unternehmen, das ihn an die Spitze der Technologiewelt katapultierte. Seine Visionen und seine F\u00fchrungsqualit\u00e4ten trieben die Computerrevolution voran und l\u00e4uteten ein Zeitalter der digitalen Konnektivit\u00e4t ein, das die Weltwirtschaft f\u00fcr immer ver\u00e4ndern sollte. Doch anstatt sich auf seinen Lorbeeren auszuruhen, kanalisierte Gates seinen unternehmerischen Scharfsinn und seine enormen Ressourcen in ein zweites, noch ehrgeizigeres Projekt: die L\u00f6sung einiger der schwierigsten Probleme der Welt. Im Jahr 2000 unternahm Gates einen k\u00fchnen zweiten Schritt und gr\u00fcndete\u00a0<a href=\"https:\/\/www.gatesfoundation.org\/\" target=\"_blank\" rel=\"noopener\">die Bill &amp; Melinda Gates Stiftung<\/a>\u00a0mit seiner damaligen Ehefrau. In den letzten zwei Jahrzehnten hat sich die Stiftung zu einer der einflussreichsten philanthropischen Institutionen der Welt entwickelt und verf\u00fcgt \u00fcber ein gewaltiges Stiftungsverm\u00f6gen von $23,5 Milliarden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7d0a89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7d0a89\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe0370e\" data-id=\"fe0370e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-174d18d2 elementor-widget elementor-widget-text-editor\" data-id=\"174d18d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><br><\/h3><h3>Investitionen in eine ges\u00fcndere Zukunft<br><\/h3>\n<p><span style=\"font-weight: 400;\">Gates hat immer wieder bewiesen, dass er bereit ist, mutige Investitionen in risikoreiche und lohnende Projekte zu t\u00e4tigen, die sich mit weit verbreiteten globalen Problemen befassen. Seine Stiftung hat mehr als $2,5 Milliarden f\u00fcr den Kampf gegen Malaria und mehr als $1 Milliarde f\u00fcr die Forschung zur Verhinderung der \u00dcbertragung von HIV bereitgestellt. Das bemerkenswerteste Beispiel f\u00fcr seinen philanthropischen Mut ist sein Engagement im Kampf gegen COVID-19. Gates war einer der ersten, der vor der Gefahr einer weltweiten Pandemie gewarnt hat. Seine Stiftung hat bis zu $1 Milliarde f\u00fcr den weltweiten Kampf gegen COVID-19 bereitgestellt, einschlie\u00dflich der Finanzierung der Entwicklung von Impfstoffen, der Erkennung und Behandlung.<\/span><\/p>\n<h3>&nbsp;<\/h3>\n<h3>Investitionen in eine gr\u00fcnere Zukunft<\/h3>\n<p>Gates' Initiativen zum Klimawandel sind ein weiteres Paradebeispiel f\u00fcr seinen vision\u00e4ren Ansatz. \u00dcber Breakthrough Energy, ein von ihm 2015 gegr\u00fcndetes Unternehmen, hat Gates in Dutzende von Unternehmen investiert, die innovative Wege zur Reduzierung von Kohlenstoffemissionen erforschen. Er hat zugesagt, in den n\u00e4chsten f\u00fcnf Jahren $2 Milliarden in die Forschung und Entwicklung sauberer Energien zu investieren, um die eskalierende Klimakrise zu bek\u00e4mpfen. Er hat auch ein Projekt namens CarbonCure unterst\u00fctzt, das Kohlendioxid aus der Atmosph\u00e4re auff\u00e4ngt und in Beton einpresst, wodurch es effektiv gebunden wird. Gates ist auch ein \u00f6ffentlicher Bef\u00fcrworter der Kernkraft als zuverl\u00e4ssige, skalierbare und emissionsfreie Energiequelle. Er ist Mitbegr\u00fcnder von TerraPower, einem Unternehmen, das sich der Entwicklung fortschrittlicher Kernreaktoren zur Reduzierung von Treibhausgasemissionen widmet.<\/p>\n<h3>&nbsp;<\/h3>\n<h3>Neue Avantgarde der Philantrophie<\/h3>\n<p>Gates' philanthropisches Engagement erstreckt sich auch auf die Finanzierung von Bildungs- und Aufkl\u00e4rungsprogrammen zum Klimawandel. Im Jahr 2021 verfasste er das Buch \"How to Avoid a Climate Disaster\", in dem er die enorme Herausforderung der Eind\u00e4mmung des Klimawandels aufschl\u00fcsselt und sowohl bestehende L\u00f6sungen als auch notwendige Innovationen skizziert. Dies zeigt, wie sehr er sich daf\u00fcr einsetzt, die \u00d6ffentlichkeit in diese kritische Diskussion einzubeziehen. Durch sein beharrliches Eintreten und seine Vordenkerrolle hat Gates ma\u00dfgeblich dazu beigetragen, die Vorstellung davon, was es bedeutet, ein Philanthrop zu sein, neu zu gestalten. Sein proaktives Engagement hat eine neue Generation wohlhabender Menschen dazu inspiriert, ihre Ressourcen zur Verbesserung der Gesellschaft einzusetzen.<\/p><p><br><\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Bill Gates ist nicht nur ein Beispiel f\u00fcr immensen finanziellen Erfolg, sondern auch f\u00fcr einen tiefgreifenden gesellschaftlichen Einfluss. Mit einem gesch\u00e4tzten Nettoverm\u00f6gen von $116,1 Milliarden im Jahr 2023 hat Gates den Begriff des Reichtums f\u00fcr unsere Zeit neu erfunden und ihn von einer blo\u00dfen Anh\u00e4ufung von Geld in eine Kraft f\u00fcr den globalen Wandel verwandelt.<\/p>","protected":false},"author":12,"featured_media":13943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","two_page_speed":[],"footnotes":""},"categories":[82,184,86,73,57,89,67],"tags":[],"class_list":["post-10404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-philantrophy","category-all-insights","category-explore-by-entity","category-explore-by-topic","category-lifestyle","category-multi-family-office","category-philantropy"],"_links":{"self":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/10404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/comments?post=10404"}],"version-history":[{"count":26,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/10404\/revisions"}],"predecessor-version":[{"id":10910,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts\/10404\/revisions\/10910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media\/13943"}],"wp:attachment":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/media?parent=10404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories?post=10404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/tags?post=10404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}