{"id":61,"count":12,"description":"","link":"https:\/\/altoo.io\/de\/category\/economic-outlook\/key-dates\/","name":"Wichtige Daten","slug":"wichtige-daten","taxonomy":"category","parent":55,"meta":[],"_links":{"self":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/categories\/55"}],"wp:post_type":[{"href":"https:\/\/altoo.io\/de\/wp-json\/wp\/v2\/posts?categories=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}